{"id":13548,"date":"2024-04-08T12:14:31","date_gmt":"2024-04-08T12:14:31","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/"},"modified":"2024-04-28T10:31:14","modified_gmt":"2024-04-28T10:31:14","slug":"separation-paiement-charge","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/","title":{"rendered":"S\u00e9paration et paiement des charges"},"content":{"rendered":"<p>Avec mon mari nous sommes s\u00e9par\u00e9s depuis 6 ans, il donne 170 \u20ac pour notre fils, la moiti\u00e9 du loyer et l&rsquo;EDF. Depuis vendredi il a fait couper l&rsquo;EDF et ne veut plus payer. Que dois-je faire pour qu&rsquo;il paye. Je suis oblig\u00e9e de refaire ouvrir l&rsquo;EDF&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec mon mari nous sommes s\u00e9par\u00e9s depuis 6 ans, il donne 170 \u20ac pour notre fils, la moiti\u00e9 du loyer et l&rsquo;EDF. Depuis vendredi il a fait couper l&rsquo;EDF et ne veut plus payer. Que dois-je faire pour qu&rsquo;il paye. Je suis oblig\u00e9e de refaire ouvrir l&rsquo;EDF&#8230;<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[47,58],"class_list":["post-13548","question","type-question","status-publish","hentry","tag-questions-pension-alimentaire","tag-questions-prestation-compensatoire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Avec mon mari nous sommes s\u00e9par\u00e9s depuis 6 ans, il donne 170 \u20ac pour notre fils, la moiti\u00e9 du loyer et l&rsquo;EDF. Depuis vendredi il a fait couper l&rsquo;EDF et ne veut plus payer. Que dois-je faire pour qu&rsquo;il paye. Je suis oblig\u00e9e de refaire ouvrir l&rsquo;EDF&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:31:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/separation-paiement-charge\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/separation-paiement-charge\\\/\",\"name\":\"S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:14:31+00:00\",\"dateModified\":\"2024-04-28T10:31:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/separation-paiement-charge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/separation-paiement-charge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/separation-paiement-charge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9paration et paiement des charges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/","og_locale":"fr_FR","og_type":"article","og_title":"S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce","og_description":"Avec mon mari nous sommes s\u00e9par\u00e9s depuis 6 ans, il donne 170 \u20ac pour notre fils, la moiti\u00e9 du loyer et l&rsquo;EDF. Depuis vendredi il a fait couper l&rsquo;EDF et ne veut plus payer. Que dois-je faire pour qu&rsquo;il paye. Je suis oblig\u00e9e de refaire ouvrir l&rsquo;EDF&#8230;","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:31:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/","name":"S\u00e9paration et paiement des charges &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:14:31+00:00","dateModified":"2024-04-28T10:31:14+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/separation-paiement-charge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"S\u00e9paration et paiement des charges"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/13548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=13548"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=13548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}