{"id":13364,"date":"2024-04-08T12:14:18","date_gmt":"2024-04-08T12:14:18","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/"},"modified":"2024-04-28T10:28:54","modified_gmt":"2024-04-28T10:28:54","slug":"bien-immobilier-refus-vendre","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/","title":{"rendered":"Mon conjoint refuse de vendre un bien immobilier commun : que faire ?"},"content":{"rendered":"<p>Bonjour, ma conjointe et moi sommes s\u00e9par\u00e9s depuis 7 ans. J&rsquo;ai obtenu la r\u00e9sidence officielle de ma fille. Je lui propose depuis 2007 de lui racheter sa part de la maison acquise en indivision 50\/50, dans laquelle je r\u00e9side avec ma fille. Mon ex ne paie q&rsquo;un tiers du remboursement du cr\u00e9dit. Elle refuse de me vendre sa part bien que je lui ai envoy\u00e9 le tableau liquidatif apr\u00e8s conseil pris aupr\u00e8s d&rsquo;un notaire. Elle refuse \u00e9galement de payer les quelques travaux effectu\u00e9s depuis 2007. Comment faire pour me sortir de cette situation ? Merci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, ma conjointe et moi sommes s\u00e9par\u00e9s depuis 7 ans. J&rsquo;ai obtenu la r\u00e9sidence officielle de ma fille. Je lui propose depuis 2007 de lui racheter sa part de la maison acquise en indivision 50\/50, dans laquelle je r\u00e9side avec ma fille. Mon ex ne paie q&rsquo;un tiers du remboursement du cr\u00e9dit. Elle refuse de [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[33,72,18],"class_list":["post-13364","question","type-question","status-publish","hentry","tag-questions-bien-immobilier","tag-questions-partage","tag-questions-refus"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour, ma conjointe et moi sommes s\u00e9par\u00e9s depuis 7 ans. J&rsquo;ai obtenu la r\u00e9sidence officielle de ma fille. Je lui propose depuis 2007 de lui racheter sa part de la maison acquise en indivision 50\/50, dans laquelle je r\u00e9side avec ma fille. Mon ex ne paie q&rsquo;un tiers du remboursement du cr\u00e9dit. Elle refuse de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:28:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/bien-immobilier-refus-vendre\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/bien-immobilier-refus-vendre\\\/\",\"name\":\"Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:14:18+00:00\",\"dateModified\":\"2024-04-28T10:28:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/bien-immobilier-refus-vendre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/bien-immobilier-refus-vendre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/bien-immobilier-refus-vendre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mon conjoint refuse de vendre un bien immobilier commun : que faire ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/","og_locale":"fr_FR","og_type":"article","og_title":"Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour, ma conjointe et moi sommes s\u00e9par\u00e9s depuis 7 ans. J&rsquo;ai obtenu la r\u00e9sidence officielle de ma fille. Je lui propose depuis 2007 de lui racheter sa part de la maison acquise en indivision 50\/50, dans laquelle je r\u00e9side avec ma fille. Mon ex ne paie q&rsquo;un tiers du remboursement du cr\u00e9dit. Elle refuse de [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:28:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/","name":"Mon conjoint refuse de vendre un bien immobilier commun : que faire ? &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:14:18+00:00","dateModified":"2024-04-28T10:28:54+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/bien-immobilier-refus-vendre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Mon conjoint refuse de vendre un bien immobilier commun : que faire ?"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/13364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=13364"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=13364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}