{"id":13299,"date":"2024-04-08T12:14:13","date_gmt":"2024-04-08T12:14:13","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/"},"modified":"2024-04-28T10:31:05","modified_gmt":"2024-04-28T10:31:05","slug":"pension-alimentaire-enfant-majeur-couple","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/","title":{"rendered":"Quand peut-on cesser de verser la pension alimentaire \u00e0 un enfant majeur ?"},"content":{"rendered":"<p>J&rsquo;ai un ami qui a 58 ans, divorc\u00e9, qui paie une pension depuis que sa fille a 4 ans. Elle a aujourd&rsquo;hui 22 ans, vie en couple (il ne sait pas si elle est mari\u00e9e) et a une enfant.<\/p>\n<p>Il se demande s&rsquo;il doit l\u00e9galement encore \u00eatre pr\u00e9lev\u00e9 mensuellement pour la pension ?<\/p>\n<p>Merci beaucoup pour votre expertise<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai un ami qui a 58 ans, divorc\u00e9, qui paie une pension depuis que sa fille a 4 ans. Elle a aujourd&rsquo;hui 22 ans, vie en couple (il ne sait pas si elle est mari\u00e9e) et a une enfant. Il se demande s&rsquo;il doit l\u00e9galement encore \u00eatre pr\u00e9lev\u00e9 mensuellement pour la pension ? Merci beaucoup [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[48,47],"class_list":["post-13299","question","type-question","status-publish","hentry","tag-questions-enfants-majeurs","tag-questions-pension-alimentaire"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?\" \/>\n<meta property=\"og:description\" content=\"J&rsquo;ai un ami qui a 58 ans, divorc\u00e9, qui paie une pension depuis que sa fille a 4 ans. Elle a aujourd&rsquo;hui 22 ans, vie en couple (il ne sait pas si elle est mari\u00e9e) et a une enfant. Il se demande s&rsquo;il doit l\u00e9galement encore \u00eatre pr\u00e9lev\u00e9 mensuellement pour la pension ? Merci beaucoup [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:31:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/pension-alimentaire-enfant-majeur-couple\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/pension-alimentaire-enfant-majeur-couple\\\/\",\"name\":\"Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:14:13+00:00\",\"dateModified\":\"2024-04-28T10:31:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/pension-alimentaire-enfant-majeur-couple\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/pension-alimentaire-enfant-majeur-couple\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/pension-alimentaire-enfant-majeur-couple\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand peut-on cesser de verser la pension alimentaire \u00e0 un enfant majeur ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/","og_locale":"fr_FR","og_type":"article","og_title":"Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?","og_description":"J&rsquo;ai un ami qui a 58 ans, divorc\u00e9, qui paie une pension depuis que sa fille a 4 ans. Elle a aujourd&rsquo;hui 22 ans, vie en couple (il ne sait pas si elle est mari\u00e9e) et a une enfant. Il se demande s&rsquo;il doit l\u00e9galement encore \u00eatre pr\u00e9lev\u00e9 mensuellement pour la pension ? Merci beaucoup [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:31:05+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/","name":"Quand cesser de verser la pension alimentaire \u00e0 un enfant majeur ?","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:14:13+00:00","dateModified":"2024-04-28T10:31:05+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/pension-alimentaire-enfant-majeur-couple\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Quand peut-on cesser de verser la pension alimentaire \u00e0 un enfant majeur ?"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/13299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=13299"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=13299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}