{"id":12812,"date":"2024-04-08T12:13:36","date_gmt":"2024-04-08T12:13:36","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/"},"modified":"2024-04-28T10:36:32","modified_gmt":"2024-04-28T10:36:32","slug":"vivre-ensemble-apres-divorce","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/","title":{"rendered":"Peut-on continuer \u00e0 vivre ensemble alors que l&rsquo;on est divorc\u00e9 ?"},"content":{"rendered":"<p>Bonsoir, apr\u00e9s un divorce \u00e0 l&rsquo;amiable et n&rsquo;ayant plus d&rsquo;enfants \u00e0 charge , est t&rsquo;il possible de vivre sous le m\u00e8me toit pour \u00e9viter \u00e0 l&rsquo;un comme \u00e0 l&rsquo;autre des frais pour se reloger ? la maison poss\u00e8de plusieurs chambres possibilit\u00e9 d &lsquo;une autre cuisine, et recevoir chacun les personnes qui lui plait ? autrement dit vivre en cohabitant, comme le fond actuellement beaucoup de personnes qui travaillent , et comme certain \u00e9tudiants ? . Merci de me dire..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonsoir, apr\u00e9s un divorce \u00e0 l&rsquo;amiable et n&rsquo;ayant plus d&rsquo;enfants \u00e0 charge , est t&rsquo;il possible de vivre sous le m\u00e8me toit pour \u00e9viter \u00e0 l&rsquo;un comme \u00e0 l&rsquo;autre des frais pour se reloger ? la maison poss\u00e8de plusieurs chambres possibilit\u00e9 d &lsquo;une autre cuisine, et recevoir chacun les personnes qui lui plait ? autrement [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[23],"class_list":["post-12812","question","type-question","status-publish","hentry","tag-questions-enfant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peut-on continuer \u00e0 vivre ensemble alors que l&#039;on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peut-on continuer \u00e0 vivre ensemble alors que l&#039;on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonsoir, apr\u00e9s un divorce \u00e0 l&rsquo;amiable et n&rsquo;ayant plus d&rsquo;enfants \u00e0 charge , est t&rsquo;il possible de vivre sous le m\u00e8me toit pour \u00e9viter \u00e0 l&rsquo;un comme \u00e0 l&rsquo;autre des frais pour se reloger ? la maison poss\u00e8de plusieurs chambres possibilit\u00e9 d &lsquo;une autre cuisine, et recevoir chacun les personnes qui lui plait ? autrement [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:36:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/vivre-ensemble-apres-divorce\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/vivre-ensemble-apres-divorce\\\/\",\"name\":\"Peut-on continuer \u00e0 vivre ensemble alors que l'on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:13:36+00:00\",\"dateModified\":\"2024-04-28T10:36:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/vivre-ensemble-apres-divorce\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/vivre-ensemble-apres-divorce\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/vivre-ensemble-apres-divorce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peut-on continuer \u00e0 vivre ensemble alors que l&rsquo;on est divorc\u00e9 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peut-on continuer \u00e0 vivre ensemble alors que l'on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/","og_locale":"fr_FR","og_type":"article","og_title":"Peut-on continuer \u00e0 vivre ensemble alors que l'on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce","og_description":"Bonsoir, apr\u00e9s un divorce \u00e0 l&rsquo;amiable et n&rsquo;ayant plus d&rsquo;enfants \u00e0 charge , est t&rsquo;il possible de vivre sous le m\u00e8me toit pour \u00e9viter \u00e0 l&rsquo;un comme \u00e0 l&rsquo;autre des frais pour se reloger ? la maison poss\u00e8de plusieurs chambres possibilit\u00e9 d &lsquo;une autre cuisine, et recevoir chacun les personnes qui lui plait ? autrement [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:36:32+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/","name":"Peut-on continuer \u00e0 vivre ensemble alors que l'on est divorc\u00e9 ? &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:13:36+00:00","dateModified":"2024-04-28T10:36:32+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/vivre-ensemble-apres-divorce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Peut-on continuer \u00e0 vivre ensemble alors que l&rsquo;on est divorc\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/12812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=12812"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=12812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}