{"id":12633,"date":"2017-02-01T00:00:00","date_gmt":"2017-02-01T00:00:00","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/"},"modified":"2024-04-28T10:35:55","modified_gmt":"2024-04-28T10:35:55","slug":"fraisproc%c3%a9dure-divorce","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/","title":{"rendered":"Paiement des honoraires de la proc\u00e9dure de divorce"},"content":{"rendered":"<p>Bonjour<br \/>\nJe suis s\u00e9par\u00e9e depuis d\u00e9cembre 2015. Mon mari ne veut pas d\u00e9bourser un seul centime pour un divorce mais consent \u00e0 divorcer \u00e0 l&rsquo;amiable si telle est ma d\u00e9cision. Nous n&rsquo;avons aucun bien en commun. Ni d&rsquo;enfants. Puis je prendre tous les frais \u00e0 ma charge. Est ce l\u00e9gal ? Y a t&rsquo;il des facilit\u00e9s de paiement dans ce cas de figure ?<br \/>\nMerci pour votre r\u00e9ponse.<br \/>\nCordialement<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour Je suis s\u00e9par\u00e9e depuis d\u00e9cembre 2015. Mon mari ne veut pas d\u00e9bourser un seul centime pour un divorce mais consent \u00e0 divorcer \u00e0 l&rsquo;amiable si telle est ma d\u00e9cision. Nous n&rsquo;avons aucun bien en commun. Ni d&rsquo;enfants. Puis je prendre tous les frais \u00e0 ma charge. Est ce l\u00e9gal ? Y a t&rsquo;il des [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[23],"class_list":["post-12633","question","type-question","status-publish","hentry","tag-questions-enfant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc\u00e9dure-divorce\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour Je suis s\u00e9par\u00e9e depuis d\u00e9cembre 2015. Mon mari ne veut pas d\u00e9bourser un seul centime pour un divorce mais consent \u00e0 divorcer \u00e0 l&rsquo;amiable si telle est ma d\u00e9cision. Nous n&rsquo;avons aucun bien en commun. Ni d&rsquo;enfants. Puis je prendre tous les frais \u00e0 ma charge. Est ce l\u00e9gal ? Y a t&rsquo;il des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc\u00e9dure-divorce\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:35:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/fraisproc%c3%a9dure-divorce\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/fraisproc%c3%a9dure-divorce\\\/\",\"name\":\"Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2017-02-01T00:00:00+00:00\",\"dateModified\":\"2024-04-28T10:35:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/fraisproc%c3%a9dure-divorce\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/fraisproc%c3%a9dure-divorce\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/fraisproc%c3%a9dure-divorce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paiement des honoraires de la proc\u00e9dure de divorce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc\u00e9dure-divorce\/","og_locale":"fr_FR","og_type":"article","og_title":"Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour Je suis s\u00e9par\u00e9e depuis d\u00e9cembre 2015. Mon mari ne veut pas d\u00e9bourser un seul centime pour un divorce mais consent \u00e0 divorcer \u00e0 l&rsquo;amiable si telle est ma d\u00e9cision. Nous n&rsquo;avons aucun bien en commun. Ni d&rsquo;enfants. Puis je prendre tous les frais \u00e0 ma charge. Est ce l\u00e9gal ? Y a t&rsquo;il des [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc\u00e9dure-divorce\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:35:55+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/","name":"Paiement des honoraires de la proc\u00e9dure de divorce &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2017-02-01T00:00:00+00:00","dateModified":"2024-04-28T10:35:55+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/fraisproc%c3%a9dure-divorce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Paiement des honoraires de la proc\u00e9dure de divorce"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/12633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=12633"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=12633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}