{"id":12269,"date":"2018-05-03T00:00:00","date_gmt":"2018-05-03T00:00:00","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/"},"modified":"2024-04-28T10:34:35","modified_gmt":"2024-04-28T10:34:35","slug":"divorce-indivision-bien","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/","title":{"rendered":"Conserver le bien en indivision malgr\u00e9 le divorce"},"content":{"rendered":"<p>Bonjour,<\/p>\n<p>Nous souhaitons divorcer par consentement mutuel afin de nous prot\u00e9ger mutuellement mais nous souhaitons \u00e9galement continuer \u00e0 cohabiter sous le m\u00eame toit (appartement dont nous sommes propri\u00e9taires mais dont nous continuons de rembourser le pr\u00eat) jusqu&rsquo;\u00e0 la fin des \u00e9tudes de nos enfants dans 3 ans.<\/p>\n<p>Est-ce possible et sous quelles conditions ?<\/p>\n<p>Merci d&rsquo;avance pour votre retour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, Nous souhaitons divorcer par consentement mutuel afin de nous prot\u00e9ger mutuellement mais nous souhaitons \u00e9galement continuer \u00e0 cohabiter sous le m\u00eame toit (appartement dont nous sommes propri\u00e9taires mais dont nous continuons de rembourser le pr\u00eat) jusqu&rsquo;\u00e0 la fin des \u00e9tudes de nos enfants dans 3 ans. Est-ce possible et sous quelles conditions ? Merci [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[212],"class_list":["post-12269","question","type-question","status-publish","hentry","tag-questions-notaire-divorce"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour, Nous souhaitons divorcer par consentement mutuel afin de nous prot\u00e9ger mutuellement mais nous souhaitons \u00e9galement continuer \u00e0 cohabiter sous le m\u00eame toit (appartement dont nous sommes propri\u00e9taires mais dont nous continuons de rembourser le pr\u00eat) jusqu&rsquo;\u00e0 la fin des \u00e9tudes de nos enfants dans 3 ans. Est-ce possible et sous quelles conditions ? Merci [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:34:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/divorce-indivision-bien\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/divorce-indivision-bien\\\/\",\"name\":\"Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2018-05-03T00:00:00+00:00\",\"dateModified\":\"2024-04-28T10:34:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/divorce-indivision-bien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/divorce-indivision-bien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/divorce-indivision-bien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conserver le bien en indivision malgr\u00e9 le divorce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/","og_locale":"fr_FR","og_type":"article","og_title":"Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour, Nous souhaitons divorcer par consentement mutuel afin de nous prot\u00e9ger mutuellement mais nous souhaitons \u00e9galement continuer \u00e0 cohabiter sous le m\u00eame toit (appartement dont nous sommes propri\u00e9taires mais dont nous continuons de rembourser le pr\u00eat) jusqu&rsquo;\u00e0 la fin des \u00e9tudes de nos enfants dans 3 ans. Est-ce possible et sous quelles conditions ? Merci [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:34:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/","name":"Conserver le bien en indivision malgr\u00e9 le divorce &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2018-05-03T00:00:00+00:00","dateModified":"2024-04-28T10:34:35+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/divorce-indivision-bien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Conserver le bien en indivision malgr\u00e9 le divorce"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/12269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=12269"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=12269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}