{"id":11943,"date":"2024-04-08T12:12:29","date_gmt":"2024-04-08T12:12:29","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/"},"modified":"2024-04-28T10:33:19","modified_gmt":"2024-04-28T10:33:19","slug":"delai-pour-un-divorce-sans-juge","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/","title":{"rendered":"D\u00e9lai pour un divorce sans juge"},"content":{"rendered":"<p>bonjour ,<br \/>\nj&rsquo;ai engager une proc\u00e9dure de divorce par consentement mutuelle  il y a maintenant 5 mois .<br \/>\nmon mari et partir vivre et travailler a 500 km de la maison depuis maintenant 5 mois , il a accepter de divorcer par consentement mutuelle mais le probl\u00e8mes c&rsquo;est qu&rsquo;il fait tra\u00eener les chose mon avocat n&rsquo;a plus de nouvelle sont avocat a lui .<\/p>\n<p>Il essaie de me faire changer d&rsquo;avis par tout les moyens ..mails , texto, il et m\u00eame revenue passer un<br \/>\nWeek-end \u00e0 la maison sans m&rsquo;en avertir en me d\u00e9nigrant devant les enfants  qui sont \u00e2g\u00e8es de 8 ans et 13 ans .<\/p>\n<p>maintenant il me menace de demander la gardes des enfants alors qu&rsquo;il ne les vois qu&rsquo;un semaine durant les vacance scolaire ..<\/p>\n<p>Depuis j&rsquo;ai refait ma vie et je compte d\u00e9m\u00e9nager a la fin de l&rsquo;ann\u00e9e scolaire dans une autre ville .<\/p>\n<p>puis-je en parler  mes enfants m\u00eame si le divorce n&rsquo;est pas prononcer et leur pr\u00e9senter mon nouveau conjoint ?<br \/>\ncar j&rsquo;aimerais programmer mon d\u00e9m\u00e9nagement pour juillet  ou je dois attendre que Mr ce d\u00e9cide a r\u00e9pondre a mon avocat et a signer les papiers ?<\/p>\n<p>il y a t&rsquo;il une date butoire pour un divorce qui sois disant et un consentement mutuelle il pourrait faire tra\u00eener les choses encore combien de temps ?<br \/>\n je ne sais plus quoi faire a part attendre que Mr fasse avancer les choses ..<\/p>\n<p>je vous remercie par avance de votre r\u00e9ponse .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>bonjour , j&rsquo;ai engager une proc\u00e9dure de divorce par consentement mutuelle il y a maintenant 5 mois . mon mari et partir vivre et travailler a 500 km de la maison depuis maintenant 5 mois , il a accepter de divorcer par consentement mutuelle mais le probl\u00e8mes c&rsquo;est qu&rsquo;il fait tra\u00eener les chose mon avocat [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[212],"class_list":["post-11943","question","type-question","status-publish","hentry","tag-questions-notaire-divorce"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"bonjour , j&rsquo;ai engager une proc\u00e9dure de divorce par consentement mutuelle il y a maintenant 5 mois . mon mari et partir vivre et travailler a 500 km de la maison depuis maintenant 5 mois , il a accepter de divorcer par consentement mutuelle mais le probl\u00e8mes c&rsquo;est qu&rsquo;il fait tra\u00eener les chose mon avocat [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:33:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/delai-pour-un-divorce-sans-juge\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/delai-pour-un-divorce-sans-juge\\\/\",\"name\":\"D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:12:29+00:00\",\"dateModified\":\"2024-04-28T10:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/delai-pour-un-divorce-sans-juge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/delai-pour-un-divorce-sans-juge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/delai-pour-un-divorce-sans-juge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9lai pour un divorce sans juge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce","og_description":"bonjour , j&rsquo;ai engager une proc\u00e9dure de divorce par consentement mutuelle il y a maintenant 5 mois . mon mari et partir vivre et travailler a 500 km de la maison depuis maintenant 5 mois , il a accepter de divorcer par consentement mutuelle mais le probl\u00e8mes c&rsquo;est qu&rsquo;il fait tra\u00eener les chose mon avocat [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:33:19+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/","name":"D\u00e9lai pour un divorce sans juge &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:12:29+00:00","dateModified":"2024-04-28T10:33:19+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/delai-pour-un-divorce-sans-juge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"D\u00e9lai pour un divorce sans juge"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/11943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=11943"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=11943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}