{"id":11872,"date":"2019-06-04T00:00:00","date_gmt":"2019-06-04T00:00:00","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/"},"modified":"2024-04-28T10:33:04","modified_gmt":"2024-04-28T10:33:04","slug":"decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/","title":{"rendered":"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l&rsquo;enfant"},"content":{"rendered":"<p>Bonjour, j&rsquo;habite pr\u00e8s de Lorient et mon ex compagne pr\u00e8s de Bordeaux. Le jaf a d\u00e9cid\u00e9 que la remise de l&rsquo;enfant se ferait \u00e0 mi chemin et que c&rsquo;est moi qui financerai le trajet de madame car elle ne travaille pas. Dans le jugement du jaf, j&rsquo;ai la moiti\u00e9 des vacances or il n&rsquo;a pas pr\u00e9cis\u00e9 le jour et l&rsquo;heure. Pour les vacances de p\u00e2ques, mon ex m&rsquo;a dit que \u00e7a serait le samedi 13 avril or je travaille le samedi et elle le sait, quelles sont mes possibilit\u00e9s ? De plus je paie son trajet, dois je payer les 2 aller retour ou juste le trajet o\u00f9 il y a mon enfant dans sa voiture ? Derni\u00e8re question, elle a d\u00e9cid\u00e9 de prendre le bateaux pour se rendre \u00e0 Royan, pour aller ensuite au point de rendez vous qui se trouve en Vend\u00e9e, elle me demande de payer le bateau et me menace de ne pas m&#8217;emmener mon enfant si je n&rsquo;accepte pas sa requ\u00eate ?<br \/>\nmerci d&rsquo;avance pour vos r\u00e9ponses. Cordialement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, j&rsquo;habite pr\u00e8s de Lorient et mon ex compagne pr\u00e8s de Bordeaux. Le jaf a d\u00e9cid\u00e9 que la remise de l&rsquo;enfant se ferait \u00e0 mi chemin et que c&rsquo;est moi qui financerai le trajet de madame car elle ne travaille pas. Dans le jugement du jaf, j&rsquo;ai la moiti\u00e9 des vacances or il n&rsquo;a pas [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[23],"class_list":["post-11872","question","type-question","status-publish","hentry","tag-questions-enfant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l&#039;enfant &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l&#039;enfant &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour, j&rsquo;habite pr\u00e8s de Lorient et mon ex compagne pr\u00e8s de Bordeaux. Le jaf a d\u00e9cid\u00e9 que la remise de l&rsquo;enfant se ferait \u00e0 mi chemin et que c&rsquo;est moi qui financerai le trajet de madame car elle ne travaille pas. Dans le jugement du jaf, j&rsquo;ai la moiti\u00e9 des vacances or il n&rsquo;a pas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:33:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\\\/\",\"name\":\"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l'enfant &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2019-06-04T00:00:00+00:00\",\"dateModified\":\"2024-04-28T10:33:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l&rsquo;enfant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l'enfant &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l'enfant &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour, j&rsquo;habite pr\u00e8s de Lorient et mon ex compagne pr\u00e8s de Bordeaux. Le jaf a d\u00e9cid\u00e9 que la remise de l&rsquo;enfant se ferait \u00e0 mi chemin et que c&rsquo;est moi qui financerai le trajet de madame car elle ne travaille pas. Dans le jugement du jaf, j&rsquo;ai la moiti\u00e9 des vacances or il n&rsquo;a pas [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:33:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/","name":"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l'enfant &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2019-06-04T00:00:00+00:00","dateModified":"2024-04-28T10:33:04+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/decisions-du-jaf-concernant-le-mode-de-residence-de-lenfant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"D\u00e9cisions du JAF concernant le mode de r\u00e9sidence de l&rsquo;enfant"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/11872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=11872"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=11872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}