{"id":11826,"date":"2024-04-08T12:12:20","date_gmt":"2024-04-08T12:12:20","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/"},"modified":"2024-04-28T10:32:54","modified_gmt":"2024-04-28T10:32:54","slug":"la-capacite-de-discernement-de-lenfant-dans-un-divorce","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/","title":{"rendered":"La capacit\u00e9 de discernement de l&rsquo;enfant dans un divorce"},"content":{"rendered":"<p>Bonjour,<br \/>\nVoil\u00e0 nous sommes pass\u00e9 en jugement pour la garde de notre fille. Son p\u00e8re l a un week end sur deux et la moiti\u00e9 des vacances scolaires.<br \/>\nUne pension alimentaire a  \u00e9t\u00e9 fix\u00e9e par le juge.<br \/>\nDepuis le mois de d\u00e9cembre 2016 ma fille ne voit et n a plus de contact avec son p\u00e8re. Les relations \u00e9taient tendues, elle ne vou lait pas y aller. Je pr\u00e9cise que notre fille a 10 ans.<br \/>\nJe voulais savoir si la r\u00e9vision de la pension \u00e9tait possible,  mais surtout je ne veux pas que ma fille soit oblig\u00e9 par son p\u00e8re \u00e0 aller chez lui.<br \/>\nEst ce qu&rsquo;il vaut mieux que j attende l age l\u00e9gal de ma fille pour qu elle puisse avoir le choix de refuser ou non de voir son p\u00e8re ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, Voil\u00e0 nous sommes pass\u00e9 en jugement pour la garde de notre fille. Son p\u00e8re l a un week end sur deux et la moiti\u00e9 des vacances scolaires. Une pension alimentaire a \u00e9t\u00e9 fix\u00e9e par le juge. Depuis le mois de d\u00e9cembre 2016 ma fille ne voit et n a plus de contact avec son [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[29,23],"class_list":["post-11826","question","type-question","status-publish","hentry","tag-questions-divorce-sans-juge","tag-questions-enfant"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La capacit\u00e9 de discernement de l&#039;enfant dans un divorce &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La capacit\u00e9 de discernement de l&#039;enfant dans un divorce &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour, Voil\u00e0 nous sommes pass\u00e9 en jugement pour la garde de notre fille. Son p\u00e8re l a un week end sur deux et la moiti\u00e9 des vacances scolaires. Une pension alimentaire a \u00e9t\u00e9 fix\u00e9e par le juge. Depuis le mois de d\u00e9cembre 2016 ma fille ne voit et n a plus de contact avec son [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:32:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\\\/\",\"name\":\"La capacit\u00e9 de discernement de l'enfant dans un divorce &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:12:20+00:00\",\"dateModified\":\"2024-04-28T10:32:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La capacit\u00e9 de discernement de l&rsquo;enfant dans un divorce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La capacit\u00e9 de discernement de l'enfant dans un divorce &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/","og_locale":"fr_FR","og_type":"article","og_title":"La capacit\u00e9 de discernement de l'enfant dans un divorce &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour, Voil\u00e0 nous sommes pass\u00e9 en jugement pour la garde de notre fille. Son p\u00e8re l a un week end sur deux et la moiti\u00e9 des vacances scolaires. Une pension alimentaire a \u00e9t\u00e9 fix\u00e9e par le juge. Depuis le mois de d\u00e9cembre 2016 ma fille ne voit et n a plus de contact avec son [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:32:54+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/","name":"La capacit\u00e9 de discernement de l'enfant dans un divorce &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:12:20+00:00","dateModified":"2024-04-28T10:32:54+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/la-capacite-de-discernement-de-lenfant-dans-un-divorce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"La capacit\u00e9 de discernement de l&rsquo;enfant dans un divorce"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/11826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=11826"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=11826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}