{"id":11805,"date":"2024-04-08T12:12:19","date_gmt":"2024-04-08T12:12:19","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/"},"modified":"2024-04-28T10:32:49","modified_gmt":"2024-04-28T10:32:49","slug":"quest-ce-que-la-donation-au-dernier-vivant","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/","title":{"rendered":"Qu&rsquo;est ce que la donation au dernier vivant ?"},"content":{"rendered":"<p>la s\u00e9paration des \u00e9poux est act\u00e9, il y a un contrat de mariage , que ce passe t il si l&rsquo;un des deux vient \u00e0 d\u00e9c\u00e9der avant que le divorce ne soit prononc\u00e9 au sujet des biens acquit par cette personne, vont t ils \u00e0 la personne restante \u00e9tant donn\u00e9 que le divorce n&rsquo;est pas prononc\u00e9 par le juge ou ne peut elle pr\u00e9tendre \u00e0 rien?<br \/>\ncombien de temps la proc\u00e9dure de divorce peut elle dur\u00e9e avant que le juge ne prenne la d\u00e9cision d\u00e9finitive du divorce?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>la s\u00e9paration des \u00e9poux est act\u00e9, il y a un contrat de mariage , que ce passe t il si l&rsquo;un des deux vient \u00e0 d\u00e9c\u00e9der avant que le divorce ne soit prononc\u00e9 au sujet des biens acquit par cette personne, vont t ils \u00e0 la personne restante \u00e9tant donn\u00e9 que le divorce n&rsquo;est pas [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[212],"class_list":["post-11805","question","type-question","status-publish","hentry","tag-questions-notaire-divorce"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu&#039;est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"la s\u00e9paration des \u00e9poux est act\u00e9, il y a un contrat de mariage , que ce passe t il si l&rsquo;un des deux vient \u00e0 d\u00e9c\u00e9der avant que le divorce ne soit prononc\u00e9 au sujet des biens acquit par cette personne, vont t ils \u00e0 la personne restante \u00e9tant donn\u00e9 que le divorce n&rsquo;est pas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:32:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/quest-ce-que-la-donation-au-dernier-vivant\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/quest-ce-que-la-donation-au-dernier-vivant\\\/\",\"name\":\"Qu'est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:12:19+00:00\",\"dateModified\":\"2024-04-28T10:32:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/quest-ce-que-la-donation-au-dernier-vivant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/quest-ce-que-la-donation-au-dernier-vivant\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/quest-ce-que-la-donation-au-dernier-vivant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&rsquo;est ce que la donation au dernier vivant ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu'est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce","og_description":"la s\u00e9paration des \u00e9poux est act\u00e9, il y a un contrat de mariage , que ce passe t il si l&rsquo;un des deux vient \u00e0 d\u00e9c\u00e9der avant que le divorce ne soit prononc\u00e9 au sujet des biens acquit par cette personne, vont t ils \u00e0 la personne restante \u00e9tant donn\u00e9 que le divorce n&rsquo;est pas [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:32:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/","name":"Qu'est ce que la donation au dernier vivant ? &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:12:19+00:00","dateModified":"2024-04-28T10:32:49+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/quest-ce-que-la-donation-au-dernier-vivant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Qu&rsquo;est ce que la donation au dernier vivant ?"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/11805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=11805"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=11805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}