{"id":11607,"date":"2024-04-08T12:11:58","date_gmt":"2024-04-08T12:11:58","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/"},"modified":"2024-04-28T10:28:15","modified_gmt":"2024-04-28T10:28:15","slug":"les-conditions-du-divorce-sans-juge","status":"publish","type":"question","link":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/","title":{"rendered":"Les conditions du divorce sans juge"},"content":{"rendered":"<p>Bonjour,<\/p>\n<p>Ma femme a des relations extraconjugales depuis plus de 2,5 ans (j&rsquo;ai pu recenser une douzaine de relations sexuelles avec diff\u00e9rents partenaires).<br \/>\nElle loue son appartement depuis d\u00e9but 2022 mais continue de vivre avec nous la majorit\u00e9 du temps.<br \/>\nElle a d&rsquo;ailleurs eu sa derni\u00e8re relation extraconjugale hier \u00e0 son appartement, en pr\u00e9textant aller \u00ab\u00a0boire un verre\u00a0\u00bb. Dans ce cas, c&rsquo;est \u00e0 moi seul de \u00ab\u00a0compenser\u00a0\u00bb aupr\u00e8s de nos enfants (de 6 et 9 ans) pour leur dire \u00ab\u00a0maman ne mange pas avec nous ce soir et je ne sais pas quand elle va rentrer\u00a0\u00bb &#8230;<\/p>\n<p>Quel type de divorce est envisageable sachant que :<\/p>\n<p>o\tc\u2019est elle qui entretient ses contacts extra-conjugaux (et rapports sexuels r\u00e9guli\u00e8rement) &#8211; et &lsquo;tranquille&rsquo; chez elle maintenant.<br \/>\no\tc\u2019est elle qui impose vivre \u00e7a \u00e0 moi et nos 2 enfants.<br \/>\no\tForce est de constater qu\u2019elle a de nombreux sympt\u00f4mes de la d\u00e9pression : elle prend des anxiolytiques r\u00e9guli\u00e8rement, moral bas quasi permanent, mauvaise humeur quasi permanente, toujours mal quelque part (elle a d\u2019ailleurs de tr\u00e8s nombreuses consultations m\u00e9dicales \u00e0 son actif, m\u00eame avec des sp\u00e9cialistes \u2026 mais \u00ab ils ne comprennent jamais \u00bb ce qu\u2019elle dit avoir \u2026), sautes d\u2019humeur fr\u00e9quentes (parfois contre les enfants), voie toujours les choses n\u00e9gativement \u2026 et elle refuse cat\u00e9goriquement de se soigner (via une th\u00e9rapie psychologique par exemple).<br \/>\no\tMe concernant, un tr\u00e8s grave accident de VTT \u00e0 21 ans occasionne aujourd\u2019hui des s\u00e9quelles permanentes qui justifie mon statut de travailleur handicap\u00e9.<br \/>\nEt ma femme a clairement et largement utilis\u00e9 contre moi mes handicaps pour d\u00e9marrer ses activit\u00e9s et \u00ab rester comme \u00e7a\u00a0\u00bb depuis 2,5 ans. Je trouve  particuli\u00e8rement immoral qu&rsquo;elle me reproche mes handicaps et s&rsquo;en serve pour justifier ses agissements ! Cette discrimination est condamn\u00e9e dans le milieu professionnel, dans quelle mesure ce qu&rsquo;elle me fait subir peut \u00ab\u00a0peser dans la balance\u00a0\u00bb ? Car elle a clairement utilis\u00e9 mes \u00ab\u00a0faiblesses\u00a0\u00bb (notamment la condition physique que je n&rsquo;ai plus, troubles neurologiques) pour d\u00e9marrer et entretenir ses relations extra-conjugales, pour me dit-elle \u00ab profiter de la vie \u00bb.<br \/>\no\tAvec le recul, je me demande m\u00eame si ma femme ne m\u2019aurait pas \u00ab utilis\u00e9 \u00bb seulement pour se sortir rapidement de son mariage pr\u00e9c\u00e9dent \u2026 car il s\u2019agit de son second mariage. Et le s\u00e9quencement de son premier a une curieuse ressemblance (vie commune puis mariage puis achat maison puis divorce car elle se serait lass\u00e9e). N\u2019aurait-elle pas tromp\u00e9 son premier mari aussi ?<br \/>\no\tA partir du moment o\u00f9 j\u2019ai \u00ab accept\u00e9 \u00bb les infid\u00e9lit\u00e9s de ma femme, elle me dit que ce n\u2019est pas possible de continuer comme \u00e7a. Et toutes les fois o\u00f9 on \u00ab s\u2019accroche \u00bb et qu\u2019elle me menace de s\u00e9paration, elle arbore un sourire et un visage joyeux qui me fait penser que c\u2019est son \u2018objectif\u2019 (d\u2019o\u00f9 mon impression qu\u2019elle s\u2019est d\u00e9j\u00e0 construit une sortie de secours) \u2026<br \/>\no\tPlus le temps passe et plus nos moments intimes sont rares : elle consentait \u00e0 un unique rapport sexuel par mois, puis une unique masturbation par semaine, puis ce n\u2019est plus rien du tout, elle me dit \u00ab tu te d\u00e9brouilles ! Et je ne veux pas le voir ni le savoir \u00bb. Et elle s\u2019offusque d\u00e8s que j\u2019ai une r\u00e9flexion ou geste qu\u2019elle peut rapprocher (de loin) \u00e0 du sexe !<br \/>\no\tElle d\u00e9jeune fr\u00e9quemment avec un de ses amants tandis qu\u2019elle refuse syst\u00e9matiquement de manger avec moi le midi, sous pr\u00e9texte d\u2019avoir trop de travail \u2026<br \/>\no\tSous couvert de me dire \u00eatre honn\u00eate avec moi, j\u2019ai souvent constat\u00e9 des messages t\u00e9l\u00e9phoniques de contacts dont elle disait ne plus avoir de nouvelles \u2026 ou des discussions avec de nouveaux contacts \u2026 ou des rdvs secrets \u2026 encore et encore !<br \/>\no\tsous pr\u00e9texte de \u00ab tranquillit\u00e9 \u00bb, ma femme loue son appartement pas loin de chez nous et de son travail pour pouvoir, me dit-elle \u00ab \u00eatre avec vous tout en ayant des moments de tranquillit\u00e9 \u00bb.<\/p>\n<p>Quelles sont mes possibilit\u00e9s pour \u00ab me retourner \u00bb sans que la nouvelle situation p\u00e9nalise moi et nos enfants ? Car je r\u00e9p\u00e8te que ses adult\u00e8res ont \u00e9t\u00e9 \/ sont \/ seront nombreux et que nous 3 sommes mis au pied du mur \u2026 et quand je lui en parle, elle me dit pr\u00e9f\u00e9rer \u00ab continuer et tout casser \u00bb que d\u2019arr\u00eater \u2026<\/p>\n<p>Merci d&rsquo;avance<br \/>\nCordialement<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, Ma femme a des relations extraconjugales depuis plus de 2,5 ans (j&rsquo;ai pu recenser une douzaine de relations sexuelles avec diff\u00e9rents partenaires). Elle loue son appartement depuis d\u00e9but 2022 mais continue de vivre avec nous la majorit\u00e9 du temps. Elle a d&rsquo;ailleurs eu sa derni\u00e8re relation extraconjugale hier \u00e0 son appartement, en pr\u00e9textant aller [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"tag-questions":[28,12,30,29],"class_list":["post-11607","question","type-question","status-publish","hentry","tag-questions-adultere","tag-questions-avocat-divorce","tag-questions-divorce-amiable","tag-questions-divorce-sans-juge"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Bonjour, Ma femme a des relations extraconjugales depuis plus de 2,5 ans (j&rsquo;ai pu recenser une douzaine de relations sexuelles avec diff\u00e9rents partenaires). Elle loue son appartement depuis d\u00e9but 2022 mais continue de vivre avec nous la majorit\u00e9 du temps. Elle a d&rsquo;ailleurs eu sa derni\u00e8re relation extraconjugale hier \u00e0 son appartement, en pr\u00e9textant aller [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-28T10:28:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/les-conditions-du-divorce-sans-juge\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/les-conditions-du-divorce-sans-juge\\\/\",\"name\":\"Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2024-04-08T12:11:58+00:00\",\"dateModified\":\"2024-04-28T10:28:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/les-conditions-du-divorce-sans-juge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/les-conditions-du-divorce-sans-juge\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/questions\\\/les-conditions-du-divorce-sans-juge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les conditions du divorce sans juge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/","og_locale":"fr_FR","og_type":"article","og_title":"Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce","og_description":"Bonjour, Ma femme a des relations extraconjugales depuis plus de 2,5 ans (j&rsquo;ai pu recenser une douzaine de relations sexuelles avec diff\u00e9rents partenaires). Elle loue son appartement depuis d\u00e9but 2022 mais continue de vivre avec nous la majorit\u00e9 du temps. Elle a d&rsquo;ailleurs eu sa derni\u00e8re relation extraconjugale hier \u00e0 son appartement, en pr\u00e9textant aller [&hellip;]","og_url":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-28T10:28:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/","url":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/","name":"Les conditions du divorce sans juge &#8211; Avocat GC - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2024-04-08T12:11:58+00:00","dateModified":"2024-04-28T10:28:15+00:00","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/questions\/les-conditions-du-divorce-sans-juge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Les conditions du divorce sans juge"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question\/11607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/question"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/question"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=11607"}],"wp:term":[{"taxonomy":"tag-questions","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/tag-questions?post=11607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}