{"id":5508,"date":"2018-06-07T00:00:00","date_gmt":"2018-06-07T00:00:00","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/bas-en-basset\/"},"modified":"2024-04-11T10:28:54","modified_gmt":"2024-04-11T10:28:54","slug":"bas-en-basset","status":"publish","type":"page","link":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/","title":{"rendered":"Avocat Divorce \u00e0 Bas-en-Basset (43)"},"content":{"rendered":"<h2>VOTRE DIVORCE \u00c0 BAS-EN-BASSET EN 1 MOIS<\/h2>\n<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/fr.trustpilot.com\/review\/avocat-gc.com?utm_medium=Trustbox&#038;utm_source=EmailNewsletter2\" target=\"_blank\" style=\"text-decoration: none;\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png\" border=\"0\" height=\"24\" alt=\"Trustpilot Logo\" style=\"max-height: 24px; width: initial; margin: 0px;\" \/><img decoding=\"async\" src=\"https:\/\/emailsignature.trustpilot.com\/newsletter\/fr-FR\/2\/4f0b2b150000640005122a37\/stars@2x.png\" border=\"0\" height=\"52\" alt=\"Trustpilot Stars\" style=\"max-height: 52px; width: initial; margin: 5px 0px;\" \/><img decoding=\"async\" src=\"https:\/\/emailsignature.trustpilot.com\/newsletter\/fr-FR\/2\/4f0b2b150000640005122a37\/text@2x.png\" border=\"0\" height=\"14\" alt=\"TrustScore\" style=\"max-height: 14px; width: initial; margin: 0px;\" \/><\/a><\/p>\n<\/p>\n<p> J&rsquo;INTERVIENS DANS TOUTE LA FRANCE <a href=\"http:\/\/avocat-gc.com\/divorce\/avocat-divorce\/paris\/\" rel=\"nofollow noopener\" title=\"\" target=\"_parent\">Notre cabinet \u00e0 Paris<\/a> : 42 Rue de L\u00fcbeck, 75116 Paris 01 47 04 25 40<\/p>\n<h3>1 &#8211; Le rendez-vous<\/h3>\n<p class=\"img-right\"><img decoding=\"async\" alt=\"Avocat Divorce \u00e0 Bas-en-Basset (43)\" title=\"Avocat Divorce \u00e0 Bas-en-Basset (43)\" width=\"170\" border=\"2\" src=\"\/divorce\/wp-content\/uploads\/2024\/04\/divorce-consentement-mutuel.png\" \/><\/p>\n<p align=\"justify\">La premi\u00e8re \u00e9tape de votre divorce consiste en un entretien avec notre avocat. Nous sommes comp\u00e9tents pour vous divorcer dans la Haute-Loire, en Auvergne-Rhone-Alpes. Pour prendre un rendez-vous, il suffit de nous contacter par t\u00e9l\u00e9phone au 01.47.04.25.40 ou par email \u00e0 l&rsquo;adresse <a href=\"mailto:info@avocat-gc.com\">info@avocat-gc.com<\/a>. Lors de ce rendez-vous :\n<\/p>\n<p>Nous vous expliquerons le d\u00e9roulement de votre proc\u00e9dure de divorce.<br \/>\nVotre avocat r\u00e9pondra \u00e0 toutes vos questions avant, pendant et suite \u00e0 votre divorce.<br \/>\nNous r\u00e9digerons votre convention de divorce<\/p>\n<h3>2 &#8211; La signature<\/h3>\n<p class=\"img-left\"><img decoding=\"async\" alt=\"Avocat Divorce sans juge Bas-en-Basset (43)\" title=\" Avocat Divorce sans juge Bas-en-Basset  (43)\" width=\"170\" border=\"2\" src=\"\/divorce\/wp-content\/uploads\/2024\/04\/divorce-sans-avocat.jpg\" \/><\/p>\n<p align=\"justify\">D\u00e9sormais, il n&rsquo;est plus n\u00e9cessaire de se pr\u00e9senter devant le Juge aux Affaires Familiales. Votre projet de convention de divorce vous sera transmis directement par courrier recommand\u00e9 avec accus\u00e9 de r\u00e9ception. Vous aurez un d\u00e9lai de reflexion de 15 jours avant de signer et nous renvoyer le projet de convention.Une fois les documents sign\u00e9s, la convention est envoy\u00e9e par notre cabinet au notaire qui enregistrera votre divorce en lui donnant force ex\u00e9cutoire et date certaine.    DIVORCE DEVANT LE JUGE :  Dans certains cas, il est toujours possible de\u00a0divorcer \u00e0 l&rsquo;amiable devant le Juge. Cette proc\u00e9dure est constitu\u00e9e d&rsquo;une audience au tribunal devant le Juge aux Affaires Familiales \u00e0 laquelle il est obligatoire d&rsquo;assister ainsi que votre avocat.   \u00c0 SAVOIR :\u00a0La proc\u00e9dure de divorce sans juge n&rsquo;est valable que dans le cadre d&rsquo;un divorce \u00e0 l&rsquo;amiable. Si tout d\u00e9saccord entre les \u00e9poux venait \u00e0 se produire, il faudrait alors opter pour un divorce contentieux qui se r\u00e9glera au terme de plusieurs audiences au tribunal:<\/p>\n<p class=\"img-right\"><img decoding=\"async\" align=\"right\" alt=\"Avocat Divorce TGI Le Puy-en-Velay (43)\" title=\"Avocat Divorce TGI Le Puy-en-Velay (43)\" width=\"80\" border=\"2\" src=\"\/divorce\/wp-content\/uploads\/2024\/04\/tgi\/tgi-palais-justice-paris.jpg\" \/><\/p>\n<\/p>\n<p>  Tribunal de grande instance Le Puy-en-Velay place du Breuil CS90335 43011 LE PUY EN VELAY CEDEXT\u00e9l : 04 71 09 05 70 \/\/ Fax : 04 71 02 54 52Du Lundi au Vendredi : de 08h30 \u00e0 12h00 de 13h30 \u00e0 17h00<\/p>\n<h3> 3 &#8211; L&rsquo;enregistrement<\/h3>\n<p class=\"img-right\"><img decoding=\"async\" align=\"left\" alt=\"Avocat Divorce Amiable Bas-en-Basset (43)\" title=\"Avocat Divorce Amiable Bas-en-Basset (43)\" width=\"170\" border=\"2\" src=\"\/divorce\/wp-content\/uploads\/2024\/04\/divorce-simple.png\" style=\"padding:5px;margin-right: 5px;\" \/><\/p>\n<p align=\"justify\">Suite \u00e0 ce rapide rendez-vous :<\/p>\n<p>nous vous adressons l&rsquo;attestation d&rsquo;enregistrement de divorce d\u00e8s r\u00e9ception au cabinet,<br \/>\nnous accomplissons les formalit\u00e9s d&rsquo;inscription de votre divorce sur vos actes d&rsquo;\u00e9tat civil,<br \/>\nnous vous fournissons les attestations n\u00e9c\u00e9ssaires dans l&rsquo;attente de votre jugement,<br \/>\nnous vous assistons tout au long de la proc\u00e9dure par t\u00e9l\u00e9phone et par email.<\/p>\n<p align=\"justify\">Vous souhaitez divorcer \u00e0 Bas-en-Basset (43) ? Merci de nous adresser le devis ci-dessous afin que nous puissions faire le point sur votre situation:<\/p>\n<\/p>\n<p><a href=\"http:\/\/avocat-gc.com\/divorce\/avocat-divorce-10-ans-dexperience\/\" rel=\"nofollow noopener\" target=\"_parent\">\u25ba DEVIS: AVOCAT DIVORCE \u00c0  BAS-EN-BASSET <\/a><\/p>\n<h3> 4 &#8211; Divorcer sans juge \u00e0 Bas-en-Basset (43)<\/h3>\n<p align=\"justify\">Le divorce sans juge est la proc\u00e9dure de divorce la plus simple et rapide Pour engager ce type de proc\u00e9dure, il faut \u00eatre d&rsquo;accord sur chaque point de la convention de divorce r\u00e9dig\u00e9e au sein de notre cabinet lors de votre premier rendez-vous. Pour conna\u00eetre chaque \u00e9tape d&rsquo;un divorce sans juge \u00e0 Bas-en-Basset (43), veuillez suivre le lien ci-dessous:<\/p>\n<p><a href=\"https:\/\/avocat-gc.com\/divorce\/avocat-divorce-amiable-sans-juge-bas-en-basset-43\/\" class=\"lien-ville\">AVOCAT DIVORCE AMIABLE SANS JUGE BAS-EN-BASSET (43)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VOTRE DIVORCE \u00c0 BAS-EN-BASSET EN 1 MOIS J&rsquo;INTERVIENS DANS TOUTE LA FRANCE Notre cabinet \u00e0 Paris : 42 Rue de L\u00fcbeck, 75116 Paris 01 47 04 25 40 1 &#8211; Le rendez-vous La premi\u00e8re \u00e9tape de votre divorce consiste en un entretien avec notre avocat. Nous sommes comp\u00e9tents pour vous divorcer dans la Haute-Loire, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7084,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-ville.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"priorite":[],"class_list":["post-5508","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce<\/title>\n<meta name=\"description\" content=\"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T10:28:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/\",\"name\":\"Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emailsignature.trustpilot.com\\\/logo\\\/n\\\/2\\\/logo@2x.png\",\"datePublished\":\"2018-06-07T00:00:00+00:00\",\"dateModified\":\"2024-04-11T10:28:54+00:00\",\"description\":\"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emailsignature.trustpilot.com\\\/logo\\\/n\\\/2\\\/logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/emailsignature.trustpilot.com\\\/logo\\\/n\\\/2\\\/logo@2x.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/bas-en-basset\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avocat Divorce\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/avocat-divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avocat Divorce \u00e0 Bas-en-Basset (43)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce","description":"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/","og_locale":"fr_FR","og_type":"article","og_title":"Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce","og_description":"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge","og_url":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/","og_site_name":"Avocat GC - Avocat Divorce","article_modified_time":"2024-04-11T10:28:54+00:00","og_image":[{"url":"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/","url":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/","name":"Avocat Divorce \u00e0 Bas-en-Basset (43) - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/#primaryimage"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/#primaryimage"},"thumbnailUrl":"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png","datePublished":"2018-06-07T00:00:00+00:00","dateModified":"2024-04-11T10:28:54+00:00","description":"Divorcez \u00e0 Bas-en-Basset (43) en 1 mois \u00e0 partir de 425\u20ac TTC. Contactez un Avocat divorce au \u260e 01.47.04.25.40 . Recevez un devis gratuit et imm\u00e9diat pour votre divorce. Cabinet Gueguen-Carroll. Divorce amiable - Divorce sans juge","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/#primaryimage","url":"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png","contentUrl":"https:\/\/emailsignature.trustpilot.com\/logo\/n\/2\/logo@2x.png"},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/bas-en-basset\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Avocat Divorce","item":"https:\/\/avocat-gc.com\/divorce\/avocat-divorce\/"},{"@type":"ListItem","position":3,"name":"Avocat Divorce \u00e0 Bas-en-Basset (43)"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/5508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/comments?post=5508"}],"version-history":[{"count":0,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/5508\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/7084"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=5508"}],"wp:term":[{"taxonomy":"priorite","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/priorite?post=5508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}