{"id":4197,"date":"2018-06-03T00:00:00","date_gmt":"2018-06-03T00:00:00","guid":{"rendered":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/"},"modified":"2018-06-03T00:00:00","modified_gmt":"2018-06-03T00:00:00","slug":"convention-mourmelon-le-grand","status":"publish","type":"page","link":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/","title":{"rendered":"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention"},"content":{"rendered":"<p><a href=\"\/divorce\/avocat-divorce\/mourmelon-le-grand\/\" rel=\"nofollow\"> \u25c4 Avocat divorce sans juge Mourmelon-le-Grand (51)<\/a><\/p>\n<p> T\u00e9l\u00e9charger Convention avocat divorce sans juge Mourmelon-le-Grand (51)<\/p>\n<h2><img decoding=\"async\" src=\"\/divorce\/sites\/all\/themes\/divorce\/images\/lg.png\" align=\"left\" alt=\"Exemple convention divorce sans juge Mourmelon-le-Grand (51)\" title=\"Exemple convention divorce sans juge Mourmelon-le-Grand (51)\" \/>MOD\u00c8LE DE CONVENTION DIVORCE SANS JUGEMOURMELON-LE-GRAND (51)Portant r\u00e8glement complet des effets du divorce<\/h2>\n<p>(Article 229 et suiv. du Code Civil, 1374, 1193 et 1195 du Code civil, Article 66-3-1 de la loi du 31 D\u00e9cembre 1971 portant r\u00e9forme de certaines professions judiciaires et juridiques, Article 6 de l\u2019Ordonnance du 10 F\u00e9vrier 2016)Article 1374 du Code civil : \u00ab L&rsquo;acte sous signature priv\u00e9e contresign\u00e9 par les avocats de chacune des parties ou par l&rsquo;avocat de toutes les parties fait foi de l&rsquo;\u00e9criture et de la signature des parties, tant \u00e0 leur \u00e9gard qu&rsquo;\u00e0 celui de leurs h\u00e9ritiers ou ayants cause. La proc\u00e9dure de faux pr\u00e9vue par le code de proc\u00e9dure civile lui est applicable. Cet acte est dispens\u00e9 de toute mention manuscrite exig\u00e9e par la loi. \u00bbArticle 66-3-1 de la loi du 31 D\u00e9cembre 1971 : \u00ab En contresignant un acte sous seing priv\u00e9, l&rsquo;avocat atteste avoir \u00e9clair\u00e9 pleinement la ou les parties qu&rsquo;il conseille sur les cons\u00e9quences juridiques de cet acte. \u00bb<\/p>\n<p align=\"justify\">ENTRE LES SOUSSIGN\u00c9S :Madame [NOM DE NAISSANCE] [PR\u00c9NOM], n\u00e9e le [DATE DE NAISSANCE] \u00e0 [LIEU DE NAISSANCE] , de nationalit\u00e9 [NATIONALIT\u00c9], demeurant [ADRESSE]\u00a051400 MOURMELON-LE-GRAND , affili\u00e9e \u00e0 la caisse d\u2019assurance maladie de la Marne\u00a051086 REIMS\u00a0sous le num\u00e9ro [N\u00b0 DE S\u00c9CURIT\u00c9 SOCIALE]<\/p>\n<p align=\"justify\">Ayant pour avocat : Cabinet d\u2019avocats Lawie\u2019s, SELARL au capital social de 10.000\u20ac repr\u00e9sent\u00e9e par son g\u00e9rant Ma\u00eetre Julien GUEGUEN-CARROLL, Avocat au barreau de Paris, 32 rue Miollis 75015 PARIS &#8211; T\u00e9l : 01.47.04.25.40 &#8211; Fax : 01.47.04.25.41 &#8211; Palais : C 307ETMonsieur [NOM] [PR\u00c9NOM], n\u00e9 le [DATE DE NAISSANCE] \u00e0 [LIEU DE NAISSANCE] , de nationalit\u00e9 NATIONALIT\u00c9, demeurant [ADRESSE]\u00a0[VILLE],\u00a0affili\u00e9 \u00e0 la caisse d\u2019assurance maladie\u00a0de\u00a0[VILLE]\u00a0sous le num\u00e9ro [N\u00b0 DE S\u00c9CURIT\u00c9 SOCIALE]<\/p>\n<p align=\"justify\">Ayant pour avocat : [COORDONN\u00c9ES DE L&rsquo;AVOCAT]Se sont entendus sur la rupture de leur mariage et ses effets, et ont souhait\u00e9 voir constater leur accord dans le cadre de la pr\u00e9sente convention sous forme d\u2019acte sous seing priv\u00e9 contresign\u00e9 par avocats conform\u00e9ment \u00e0 l\u2019article 1374 du Code Civil qui dispose :<\/p>\n<\/p>\n<p>PR\u00c9AMBULE \u2013 D\u00c9CLARATION DES \u00c9POUX<\/p>\n<h3>COMPETENCE ET LOI APPLICABLE<\/h3>\n<h2 class=\"accordion-header\">\u00a0\u00a0\u00c9poux europ\u00e9en <\/h2>\n<p align=\"justify\">Madame [NOM DE NAISSANCE] [PR\u00c9NOM] est de nationalit\u00e9 [NATIONALIT\u00c9].Monsieur [NOM] [PR\u00c9NOM] est de nationalit\u00e9 [NATIONALIT\u00c9].Conform\u00e9ment \u00e0 l\u2019article 3 a) du R\u00e8glement 2201\/2003 du 27 novembre 2003, dit R\u00e8glement Bruxelles II bis, \u00ab sont comp\u00e9tentes pour statuer sur les questions relatives au divorce [\u2026], les juridictions de l&rsquo;\u00c9tat membre sur le territoire duquel se trouve, en cas de demande conjointe, la r\u00e9sidence habituelle de l&rsquo;un ou l&rsquo;autre \u00e9poux \u00bb.Madame [NOM DE NAISSANCE] [PR\u00c9NOM], demeure [ADRESSE ]\u00a051400 MOURMELON-LE-GRAND Monsieur [NOM] [PR\u00c9NOM], demeure [ADRESSE ]\u00a0\u00a0[VILLE ]Le juge fran\u00e7ais est donc comp\u00e9tent pour statuer sur la demande en divorce des \u00e9poux.En outre, conform\u00e9ment \u00e0 l\u2019article 5 1. a) du R\u00e8glement n\u00b0 1259\/2010 du 20 d\u00e9cembre 2010, entr\u00e9 en vigueur le 21 juin 2012, dit R\u00e8glement ROME III, \u00ab les \u00e9poux peuvent convenir de d\u00e9signer la loi applicable au divorce et \u00e0 la s\u00e9paration de corps, pour autant qu\u2019il s\u2019agisse de l\u2019une des lois suivantes : c) la loi de l\u2019\u00c9tat de la nationalit\u00e9 de l\u2019un des \u00e9poux au moment de la conclusion de la convention \u00bb.La loi fran\u00e7aise est donc applicable en  l\u2019esp\u00e8ce.<\/p>\n<h2 class=\"accordion-header\">\u00a0\u00a0En cas d\u2019\u00e9poux franco-marocain<\/h2>\n<p align=\"justify\">Madame [NOM DE NAISSANCE] [PR\u00c9NOM]est de nationalit\u00e9 [NATIONALIT\u00c9].Monsieur [NOM] [PR\u00c9NOM] est de nationalit\u00e9 [NATIONALIT\u00c9].Conform\u00e9ment \u00e0 l\u2019Article 11 de la convention franco-marocaine du 10 ao\u00fbt 1981 : \u201c la dissolution du mariage peut-\u00eatre prononc\u00e9e par les juridictions de celui des deux Etats sur le territoire duquel les \u00e9poux ont leur domicile commun ou avaient leur dernier domicile commun.\u201dEn l\u2019esp\u00e8ce, les \u00e9poux se sont mari\u00e9s en France par-devant l\u2019officier d\u2019\u00e9tat civil de la Mairie se sont mari\u00e9s \u00e0 LIEU DU MARIAGE, le [DATE DE MARIAGE]. Ils r\u00e9sident depuis l\u2019un et l\u2019autre sur le territoire fran\u00e7ais et avait leur domicile conjugal en France.  La Loi fran\u00e7aise est donc applicable pour statuer sur la demande en divorce des \u00e9poux. <\/p>\n<h2 class=\"accordion-header\">\u00a0\u00a0En cas d\u2019\u00e9poux franco-tunisien<\/h2>\n<p align=\"justify\">Madame [NOM DE NAISSANCE] [PR\u00c9NOM]est de nationalit\u00e9 [NATIONALIT\u00c9].Monsieur [NOM] [PR\u00c9NOM] est de nationalit\u00e9 [NATIONALIT\u00c9].Conform\u00e9ment \u00e0 l\u2019article 16-d) de la Convention bilat\u00e9rale franco-tunisienne relative \u00e0 l\u2019entraide judiciaire en mati\u00e8re civile et commerciale et \u00e0 la reconnaissance et \u00e0 l\u2019ex\u00e9cution des d\u00e9cisions judiciaires, du 28 juin 1972, \u201c La comp\u00e9tence de l\u2019autorit\u00e9 judiciaire de l\u2019Etat dans lequel la d\u00e9cision a \u00e9t\u00e9 rendue est fond\u00e9e au sens de l\u2019article pr\u00e9c\u00e9dent [\u2026], en cas d\u2019action en divorce [\u2026], lorsque le demandeur avait la nationalit\u00e9  de l\u2019Etat o\u00f9 la d\u00e9cision a \u00e9t\u00e9 rendue et r\u00e9sidait habituellement depuis au moins un an sur le territoire de cet Etat \u00e0 la date de l\u2019acte introductif d\u2019instance.\u201dMadame [NOM DE NAISSANCE] [PR\u00c9NOM] et Monsieur [NOM] [PR\u00c9NOM] se sont mari\u00e9s \u00e0 [LIEU DU MARIAGE], le [DATE DE MARIAGE] et ont fait retranscrire leur mariage aupr\u00e8s de l\u2019officier de l\u2019\u00e9tat civil [LIEU] le [DATE] Ils r\u00e9sident depuis l\u2019un et l\u2019autre sur le territoire fran\u00e7ais. A ce titre, Monsieur [NOM] [PR\u00c9NOM] est titulaire d\u2019une carte de s\u00e9jour de 10 ans. Le juge fran\u00e7ais est donc comp\u00e9tent pour conna\u00eetre de leur divorce.En outre, en l\u2019absence de stipulation r\u00e9gissant la d\u00e9termination de la loi applicable dans cette m\u00eame convention, l\u2019article 309 du code civil pr\u00e9cise que le divorce est r\u00e9gi par la loi fran\u00e7aise, notamment lorsque les \u00e9poux ont, l\u2019un et l\u2019autre, leur domicile sur le territoire fran\u00e7ais, comme c\u2019est le cas en l\u2019esp\u00e8ce.<\/p>\n<p>1.\tMariage et r\u00e9gime matrimonial :Madame [NOM DE NAISSANCE] [PR\u00c9NOM] et Monsieur [NOM] [PR\u00c9NOM] ont contract\u00e9 mariage le [DATE DE MARIAGE] par-devant l\u2019officier d\u2019\u00e9tat civil de la Mairie de [VILLE DE MARIAGE] ,Les \u00e9poux  n\u2019ont conclu aucun contrat de mariage de telle sorte qu\u2019ils sont soumis au r\u00e9gime de la communaut\u00e9 de biens r\u00e9duite aux acqu\u00eats tel que r\u00e9git par les articles 1400 et suivants du code civil.OuLes \u00e9poux  sont mari\u00e9s sous le r\u00e9gime de  [R\u00c9GIME MATRIMONIAL]  , suivant contrat re\u00e7u par Me [ NOM ], Notaire \u00e0 [VILLE].2.\tSur la pr\u00e9sence d\u2019enfants :Il n\u2019y a pas d\u2019enfant issu de ce mariageOuUn enfant est issu de ce mariage :\n<\/p>\n<p>[NOM] [PR\u00c9NOM], n\u00e9(e) le [DATE DE NAISSANCE] \u00e0 [VILLE] qui est [MINEUR(E) ou MAJEUR(E)]<br \/>\n[RENSEIGNEMENTS DEUXI\u00c8ME  ENFANT]<\/p>\n<p>3.\tSur les revenus des \u00e9poux :Madame  exerce la profession de [PROFESSION] et per\u00e7oit un revenu mensuel de [REVENU]\u20acMonsieur  exerce la profession de [PROFESSION] et per\u00e7oit un revenu mensuel de [REVENU]\u20acLes \u00e9poux confirment la r\u00e9alit\u00e9 de leur situation financi\u00e8re et patrimoniale ; ils ont remis \u00e0 chacun de leur Conseil une attestation sur l\u2019honneur, conforme aux dispositions de l\u2019article 272 du Code Civil, qui demeurera annex\u00e9e aux pr\u00e9sentes.\n<\/p>\n<h3>CONSENTEMENT DES \u00c9POUX<\/h3>\n<p align=\"justify\">En application des dispositions des articles 229, 229-1 et 229-3 du Code Civil, les \u00e9poux d\u00e9clarent express\u00e9ment qu\u2019ils ont consenti mutuellement \u00e0 leur divorce, et qu\u2019ils se sont entendus sur la rupture de leur mariage et de ses effets dans les termes de la pr\u00e9sente convention prenant forme d\u2019un acte sous signature priv\u00e9e contresign\u00e9 par avocats et d\u00e9pos\u00e9 au <a href=\"\/divorce\/definitions\/rang-des-minutes\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition rang des minutes\" target=\"\">rang des minutes<\/a> d\u2019un notaire.Chacun des avocats signataires s\u2019est assur\u00e9 du consentement de son client.<\/p>\n<h3>CONVENTION RELATIVE AUX \u00c9POUX<\/h3>\n<p>1 &#8211; Nom de l\u2019\u00e9pouse :En application de l\u2019article 264 du code civil :-\tl\u2019\u00e9pouse conservera l\u2019usage de son nom d\u2019\u00e9pouse, en plein accord avec son mari. Cet usage est consenti sans limitation de dur\u00e9e, sauf abus de la part de l\u2019\u00e9pouse.Ou-\t l\u2019\u00e9pouse reprendra l\u2019usage de son nom patronymique de jeune fille, d\u00e8s lors elle s\u2019interdit d\u2019utiliser le nom de son \u00e9poux, d\u00e8s que l\u2019acte de divorce aura acquis date certaine par d\u00e9p\u00f4t au rang des minutes d\u2019un notaire.\n<\/p>\n<p>2 \u2013 La r\u00e9sidence des \u00e9poux :Les \u00e9poux conviennent de fixer leurs domiciles respectifs aux adresses suivantes :- Madame [NOM DE NAISSANCE] [PR\u00c9NOM] r\u00e9side [ADRESSE ]\u00a051400 MOURMELON-LE-GRAND ,<\/p>\n<p>&#8211; Monsieur [NOM] [PR\u00c9NOM] r\u00e9side [ADRESSE ]\u00a0[VILLE]\u00a0, Il est pr\u00e9cis\u00e9 que Monsieur [NOM] (ou Madame [NOM DE NAISSANCE] ) devra quitter le domicile conjugal au plus tard dans les six mois qui suivent le prononc\u00e9 du divorce soit le jour o\u00f9 le divorce acquiert date certaine et force ex\u00e9cutoire c\u2019est-\u00e0-dire au jour du d\u00e9p\u00f4t au rang des minutes du Notaire.OuIl est pr\u00e9cis\u00e9 que la jouissance du bail aff\u00e9rent \u00e0 l\u2019ancien domicile conjugal sis [ADRESSE ]sera attribu\u00e9 \u00e0 Monsieur [NOM] \/ Madame [NOM DE NAISSANCE].3 \u2013 Les effets personnels et v\u00eatements :<\/p>\n<p align=\"justify\">Les \u00e9poux d\u00e9clarent qu\u2019ils ont repris possession de leurs v\u00eatements et effets personnels et de ce chef, \u00eatre remplis de leur droit.4 \u2013 Prestation compensatoire :<\/p>\n<p align=\"justify\">Le mariage d\u2019entre les \u00e9poux  a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9 \u00e0 la mairie de [LIEU], le [DATE].\n<\/p>\n<h2 class=\"accordion-header\"> \u00a0\u00a0Sans prestation compensatoire<\/h2>\n<p align=\"justify\">Compte tenu des situations respectives des \u00e9poux, d\u00e9crites au 3\u00b0 du pr\u00e9ambule et des d\u00e9clarations des \u00e9poux ;Compte tenu des dispositions des articles 270 et suivants du Code Civil et eu \u00e9gard aux \u00e9l\u00e9ments d\u2019appr\u00e9ciation exprim\u00e9s aux termes de l\u2019article 271 dudit Code, et pour des raisons personnelles \u00e0 chacun des \u00e9poux, il a \u00e9t\u00e9 convenu entre les \u00e9poux qu\u2019aucune <a href=\"\/divorce\/definitions\/prestation-compensatoire\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition prestation compensatoire\" target=\"\">prestation compensatoire <\/a>ne serait due de part et d\u2019autre.  Les \u00e9poux ont \u00e9t\u00e9 inform\u00e9s du caract\u00e8re irr\u00e9vocable de leur d\u00e9cision et y renoncent en toute connaissance de cause. Les \u00e9poux  reconnaissent express\u00e9ment avoir \u00e9t\u00e9 inform\u00e9s qu\u2019ils ne pourront formuler de demande ult\u00e9rieure \u00e0 ce titre.<\/p>\n<h2 class=\"accordion-header\">\u00a0\u00a0Avec prestation compensatoire<\/h2>\n<p align=\"justify\">Compte tenu des situations respectives des \u00e9poux, d\u00e9crites au 3\u00b0 du pr\u00e9ambule ;Compte tenu des dispositions des articles 270 et suivants du Code Civil et eu \u00e9gard aux \u00e9l\u00e9ments d\u2019appr\u00e9ciation exprim\u00e9s aux termes de l\u2019article 271 dudit Code, et pour des raisons personnelles \u00e0 chacun des \u00e9poux, il a \u00e9t\u00e9 convenu entre les \u00e9poux que Monsieur  verserait une prestation compensatoire \u00e0 Madame  d\u2019un montant de [MONTANT] \u20ac.1\u00b0 Prestation compensatoire sous forme de versement en une seule fois :La prestation compensatoire prendra la forme d\u2019un versement unique de  Monsieur \u00e0 Madame \u00e0 la date du [DATE]  par virement au compte CARPA de Maitre [NOM] , avocat de Madame.2\u00b0 Prestation compensatoire sous forme de versements p\u00e9riodiques index\u00e9s :Cette prestation compensatoire d\u2019un montant de  \u20ac sera payable sous forme de versements p\u00e9riodiques mensuels de [MONTANT] \u20ac 3\u00b0 Prestation compensatoire sous forme de rente viag\u00e8re :Monsieur et Madame  conviennent que Monsieur versera \u00e0 Madame, \u00e0 titre de prestation compensatoire, une rente viag\u00e8re sa vie durant, \u00e0 compter du jour du d\u00e9p\u00f4t de la convention de divorce au rang des minutes du notaire d\u00e9sign\u00e9, dont le montant est fix\u00e9 mensuellement \u00e0 la somme de [MONTANT]  \u20ac.4\u00b0IndexationCes versements p\u00e9riodiques seront index\u00e9s de plein droit le 1er janvier de chaque ann\u00e9e et pour la premi\u00e8re fois le [DATE]  , sur l\u2019indice national des prix \u00e0 la consommation, hors tabac, publi\u00e9 par l\u2019INSEE \u00e0 l\u2019initiative de Monsieur , selon la formule suivante :<\/p>\n<\/p>\n<p>(montant de la contribution) x (nouvel indice)  indice initialLes indices des prix \u00e0 la consommation sont consultables par l\u2019INSEE (par t\u00e9l\u00e9phone au 08.92.68.07.60 ou sur internet : <a href=\"http:\/\/www.insee.fr\">www.insee.fr<\/a>) Les \u00e9poux sont inform\u00e9s qu\u2019en application des dispositions de l\u2019article 465-1 du code de proc\u00e9dure civile, qu\u2019en cas de d\u00e9faillance du d\u00e9biteur de la pension dans le r\u00e8glement des sommes dues :1\u00b0 Le cr\u00e9ancier peut obtenir le r\u00e8glement forc\u00e9 en utilisant \u00e0 son choix une ou plusieurs voies d\u2019ex\u00e9cution suivante :- saisie-attribution entre les mains d\u2019un tiers- autres saisies- paiement direct entre les mains de l\u2019employeur (saisie-arr\u00eat sur salaire)- recouvrement direct par l\u2019interm\u00e9diaire du Procureur de la R\u00e9publique2\u00b0 <a href=\"\/divorce\/definitions\/debiteur\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition d\u00e9biteur\" target=\"\">Le d\u00e9biteur<\/a> encourt les peines des articles 227-3 du Code P\u00e9nal qui dispose que \u00ab le fait, pour une personne, de ne pas ex\u00e9cuter une d\u00e9cision judiciaire ou une convention judiciairement homologu\u00e9e lui imposant de verser au profit d&rsquo;un enfant mineur, d&rsquo;un descendant, d&rsquo;un ascendant ou du conjoint une pension, une contribution, des subsides ou des prestations de toute nature dues en raison de l&rsquo;une des obligations familiales pr\u00e9vues par le code civil, en demeurant plus de deux mois sans s&rsquo;acquitter int\u00e9gralement de cette obligation, est puni de deux ans d&#8217;emprisonnement et de 15 000 euros d&rsquo;amende.Les infractions pr\u00e9vues par le premier alin\u00e9a du pr\u00e9sent article sont assimil\u00e9es \u00e0 des abandons de famille pour l&rsquo;application du 3\u00b0 de l&rsquo;article 373 du code civil. \u00bbEt de celles de l\u2019article 227-29 du m\u00eame code qui dispose que : \u00ab Les personnes physiques coupables des infractions pr\u00e9vues au pr\u00e9sent chapitre encourent \u00e9galement les peines compl\u00e9mentaires suivantes :1\u00b0 L&rsquo;interdiction des droits civiques, civils et de famille, suivant les modalit\u00e9s d\u00e9finies \u00e0 l&rsquo;article 131-26 ;2\u00b0 La suspension, pour une dur\u00e9e de cinq ans au plus, du permis de conduire, cette suspension pouvant \u00eatre limit\u00e9e \u00e0 la conduite en dehors de l&rsquo;activit\u00e9 professionnelle ;3\u00b0 L&rsquo;annulation du permis de conduire avec interdiction de solliciter la d\u00e9livrance d&rsquo;un nouveau permis pendant cinq ans au plus ;4\u00b0 L&rsquo;interdiction, pour une dur\u00e9e de cinq ans au plus, de quitter le territoire de la R\u00e9publique ;5\u00b0 La confiscation de la chose qui a servi ou \u00e9tait destin\u00e9e \u00e0 commettre l&rsquo;infraction ou de la chose qui en est le produit ;6\u00b0 L&rsquo;interdiction, soit \u00e0 titre d\u00e9finitif, soit pour une dur\u00e9e de dix ans au plus, d&rsquo;exercer une activit\u00e9 professionnelle ou b\u00e9n\u00e9vole impliquant un contact habituel avec des mineurs ;7\u00b0 L&rsquo;obligation d&rsquo;accomplir un stage de responsabilit\u00e9 parentale, selon les modalit\u00e9s fix\u00e9es \u00e0 l&rsquo;article  131-35-1 \u00bb(\u00e9ventuellement) Les \u00e9poux conviennent, en application des dispositions de l\u2019article 279-1 et du troisi\u00e8me alin\u00e9a de l\u2019article 279 du Code Civil, qu\u2019en cas de changement importants dans les ressources ou les besoins de l\u2019une ou l\u2019autre des parties, elles pourront en demander la r\u00e9vision.<\/p>\n<p>5 &#8211; Avantages matrimoniaux :<\/p>\n<p align=\"justify\">Il est rappel\u00e9 qu\u2019en vertu des dispositions de l\u2019article 265 du code civil, le divorce emporte r\u00e9vocation de plein droit des avantages matrimoniaux qui prennent effet \u00e0 la dissolution du r\u00e9gime matrimonial ou au d\u00e9c\u00e8s de l\u2019un des \u00e9poux et des dispositions \u00e0 cause de mort accord\u00e9s par un \u00e9poux envers son conjoint par contrat de mariage ou pendant l\u2019union.Les \u00e9poux se sont consentis pendant le mariage <a href=\"\/divorce\/definitions\/donation\/\" rel=\"nofollow noopener\" title=\"\" target=\"\">une donation <\/a>selon acte dress\u00e9 le [date] par ma\u00eetre [nom], notaire \u00e0 [ville], le [date] ,  qui sera r\u00e9voqu\u00e9e de plein droit par l\u2019effet du divorce.ouLes \u00e9poux  ne s\u2019\u00e9taient consenti aucun avantage matrimonial et aucune donation.<\/p>\n<h2 class=\"accordion-header\"> \u00a0\u00a0CONVENTION RELATIVE AUX ENFANTS<\/h2>\n<p align=\"justify\">1 &#8211; L\u2019autorit\u00e9 parentale :L&rsquo;autorit\u00e9 parentale sur les ou l\u2019enfant(s) mineur(es)  n\u00e9(es) le [date(s) de naissance] sera exerc\u00e9e conjointement par les deux parents.A cet effet, ils devront notamment, prendre ensemble, dans l\u2019int\u00e9r\u00eat de leur(s) enfant(s) les d\u00e9cisions importantes concernant la sant\u00e9, l\u2019orientation scolaire, l\u2019\u00e9ducation religieuse et le changement de r\u00e9sidence.Ils devront \u00e9galement s\u2019informer de l\u2019organisation de la vie scolaire, activit\u00e9s sportives et culturelles, traitements m\u00e9dicaux, loisirs et vacances.Les parents s\u2019engagent \u00e0 permettre une libre communication de leur(s) enfant(s) avec l\u2019autre parent dans le respect de leur cadre de vie respectif, par le biais notamment de communication t\u00e9l\u00e9phonique ou tout autre support.Il est \u00e9galement rappel\u00e9 les dispositions de l\u2019article 373-2 du code civil qui dispose que : \u00ab la s\u00e9paration des parents est sans incidence sur les r\u00e8gles de d\u00e9volution de l&rsquo;exercice de l&rsquo;autorit\u00e9 parentale.<br \/>\nchacun des p\u00e8re et m\u00e8re doit maintenir des relations personnelles avec l&rsquo;enfant et respecter les liens de celui-ci avec l&rsquo;autre parent.<br \/>\ntout changement de r\u00e9sidence de l&rsquo;un des parents, d\u00e8s lors qu&rsquo;il modifie les modalit\u00e9s d&rsquo;exercice de l&rsquo;autorit\u00e9 parentale, doit faire l&rsquo;objet d&rsquo;une information pr\u00e9alable et en temps utile de l&rsquo;autre parent. en cas de d\u00e9saccord, le parent le plus diligent saisit le juge aux affaires familiales qui statue selon ce qu&rsquo;exige l&rsquo;int\u00e9r\u00eat de l&rsquo;enfant. le juge r\u00e9partit les frais de d\u00e9placement et ajuste en cons\u00e9quence le montant de la contribution \u00e0 l&rsquo;entretien et \u00e0 l&rsquo;\u00e9ducation de l&rsquo;enfant. \u00bb2 &#8211; R\u00e9sidence des enfants :La r\u00e9sidence principale de  [ nom des enfants ]sera fix\u00e9e chez la m\u00e8re.Le p\u00e8re b\u00e9n\u00e9ficiera d\u2019un libre droit de visite et d&rsquo;h\u00e9bergement.Le <a href=\"\/divorce\/definitions\/droit-de-visite-et-hebergement\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition droit de visite et d'h\u00e9bergement\" target=\"\">droit de visite et d&rsquo;h\u00e9bergement<\/a> des enfants est laiss\u00e9 \u00e0 l&rsquo;appr\u00e9ciation et \u00e0 la libre convenance des parents.N\u00e9anmoins, en cas de difficult\u00e9s, le droit de visite et d\u2019h\u00e9bergement du p\u00e8re s&rsquo;exercera de la mani\u00e8re suivante :\u00c0 tout le moins, le p\u00e8re pourra recevoir et h\u00e9berger l\u2019enfant les premier, troisi\u00e8me et \u00e9ventuellement cinqui\u00e8me fins de semaines de chaque mois du vendredi 18 heures au dimanche 19 heures, \u00e0 charge d&rsquo;aller chercher l\u2019enfant ou faire chercher au domicile ou r\u00e9sidence de la m\u00e8re et de l\u2019y reconduire ou faire reconduire.Monsieur [nom] pourra en outre recevoir et h\u00e9berger l\u2019enfant durant la moiti\u00e9 de toutes les vacances scolaires avec alternance la premi\u00e8re moiti\u00e9 les ann\u00e9es impaires et la seconde moiti\u00e9, les ann\u00e9es paires.-\t\u00e9tant pr\u00e9cis\u00e9 que sauf meilleur accord, le p\u00e8re aura la charge de venir chercher l\u2019enfant au domicile de l\u2019autre parent avec la facult\u00e9 de se substituer un digne de confiance pour venir le chercher ou le ramener,-\tla fin de semaine sera supprim\u00e9e pendant la partie des cong\u00e9s r\u00e9serv\u00e9s au parent chez lequel l\u2019enfant \u00e0 sa r\u00e9sidence habituelle,-\tla fin de semaine sera automatiquement prolong\u00e9e jusqu\u2019\u00e0 lundi, si celui-ci est f\u00e9ri\u00e9 et avanc\u00e9 au vendredi si celui-ci est f\u00e9ri\u00e9,-\tles dates de vacances \u00e0 prendre en consid\u00e9ration sont celles de l\u2019acad\u00e9mie o\u00f9 demeure actuellement l\u2019enfant,-\tle jour de la f\u00eate des m\u00e8res est r\u00e9serv\u00e9 \u00e0 la m\u00e8re et le jour de la f\u00eate des p\u00e8res au p\u00e8re,-\tlorsque la cinqui\u00e8me fin de semaine sera \u00e0 cheval sur deux mois, elle sera rattach\u00e9e en entier au mois qui prend fin,-\tsi le p\u00e8re n\u2019a pas pris l\u2019enfant en charge dans l\u2019heure pour les fins de semaine ou  dans la journ\u00e9e pour les vacances, il sera cens\u00e9 avoir renonc\u00e9 \u00e0 la totalit\u00e9 de la p\u00e9riode consid\u00e9r\u00e9e. ouLes parents exerceront une r\u00e9sidence altern\u00e9e de l\u2019enfant, du dimanche \u00e0 20h00 au dimanche \u00e0 20h00 suivant : semaine paire pour Madame ou MonsieurPour les vacances scolaires :- petites et grandes vacances scolaires:<\/p>\n<p> premi\u00e8re moiti\u00e9 les ann\u00e9es paires pour la m\u00e8re (ou le p\u00e8re).<br \/>\ndeuxi\u00e8me moiti\u00e9 les ann\u00e9es impaires pour la m\u00e8re (ou le p\u00e8re).<\/p>\n<p>    ces dispositions seront r\u00e9visables en cas de fait nouveau.ouMonsieur  [nom de l&rsquo;enfant majeur] n\u00e9 le [date de naissance] \u00e0 [ville de naissance] est majeur, l\u2019exercice de l\u2019autorit\u00e9 parentale et du droit de visite et d\u2019h\u00e9bergement n\u2019est plus applicable.3 &#8211; Sur les pensions alimentaires :Compte tenu des situations respectives des \u00e9poux, d\u00e9crites au 3\u00b0 du pr\u00e9ambule ;Monsieur [nom] s\u2019engage \u00e0 verser une pension alimentaire au titre de la contribution pour l\u2019entretien et l\u2019\u00e9ducation de l\u2019enfant, \u00e0 hauteur de [montant] euros par mois et par enfant, soit au total, la somme de [montant] euros, payable au plus tard le 5 de chaque mois, \u00e0 compter de la date \u00e0 laquelle la pr\u00e9sente convention aura acquis force ex\u00e9cutoire.La <a href=\"\/divorce\/definitions\/pension-alimentaire\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition pension alimentaire\" target=\"\">pension alimentaire<\/a> sera index\u00e9e de plein droit le 1er janvier de chaque ann\u00e9e, sur l\u2019indice national des prix \u00e0 la consommation, hors tabac, publi\u00e9 par l\u2019insee \u00e0 l\u2019initiative de Monsieur [nom ], selon la formule suivante :<\/p>\n<p>(montant de la contribution) x (nouvel indice)indice initial<\/p>\n<p>Les indices des prix \u00e0 la consommation sont consultables par l\u2019insee (par t\u00e9l\u00e9phone au 08.92.68.07.60 ou sur internet : <a href=\"http:\/\/www.insee.fr\">www.insee.fr<\/a>) Les \u00e9poux sont inform\u00e9s qu\u2019en application des dispositions de l\u2019article 465-1 du code de proc\u00e9dure civile, qu\u2019en cas de d\u00e9faillance du d\u00e9biteur de la pension dans le r\u00e8glement des sommes dues :1\u00b0 <a href=\"\/divorce\/definitions\/creancier\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition cr\u00e9ancier\" target=\"\">le cr\u00e9ancier <\/a>peut obtenir le r\u00e8glement forc\u00e9 en utilisant \u00e0 son choix une ou plusieurs voies d\u2019ex\u00e9cution suivante :- saisie-attribution entre les mains d\u2019un tiers- autres saisies- paiement direct entre les mains de l\u2019employeur (saisie-arr\u00eat sur salaire) Recouvrement direct par l\u2019interm\u00e9diaire du procureur de la r\u00e9publique 2\u00b0 le d\u00e9biteur encourt les peines des articles 227-3 du code p\u00e9nal qui dispose que  \u00ab le fait, pour une personne, de ne pas ex\u00e9cuter une d\u00e9cision judiciaire ou une convention judiciairement homologu\u00e9e lui imposant de verser au profit d&rsquo;un enfant mineur, d&rsquo;un descendant, d&rsquo;un ascendant ou du conjoint une pension, une contribution, des subsides ou des prestations de toute nature dues en raison de l&rsquo;une des obligations familiales pr\u00e9vues par le code civil, en demeurant plus de deux mois sans s&rsquo;acquitter int\u00e9gralement de cette obligation, est puni de deux ans d&#8217;emprisonnement et de 15 000 euros d&rsquo;amende.Les infractions pr\u00e9vues par le premier alin\u00e9a du pr\u00e9sent article sont assimil\u00e9es \u00e0 des abandons de famille pour l&rsquo;application du 3\u00b0 de l&rsquo;article 373 du code civil. \u00bbEt de celles de l\u2019article 227-29 du m\u00eame code qui dispose que : \u00ab les personnes physiques coupables des infractions pr\u00e9vues au pr\u00e9sent chapitre encourent \u00e9galement les peines compl\u00e9mentaires suivantes :1\u00b0 l&rsquo;interdiction des droits civiques, civils et de famille, suivant les modalit\u00e9s d\u00e9finies \u00e0 l&rsquo;article 131-26 ;2\u00b0 la suspension, pour une dur\u00e9e de cinq ans au plus, du permis de conduire, cette suspension pouvant \u00eatre limit\u00e9e \u00e0 la conduite en dehors de l&rsquo;activit\u00e9 professionnelle ;3\u00b0 l&rsquo;annulation du permis de conduire avec interdiction de solliciter la d\u00e9livrance d&rsquo;un nouveau permis pendant cinq ans au plus ;4\u00b0 l&rsquo;interdiction, pour une dur\u00e9e de cinq ans au plus, de quitter le territoire de la r\u00e9publique ;5\u00b0 la confiscation de la chose qui a servi ou \u00e9tait destin\u00e9e \u00e0 commettre l&rsquo;infraction ou de la chose qui en est le produit ;6\u00b0 l&rsquo;interdiction, soit \u00e0 titre d\u00e9finitif, soit pour une dur\u00e9e de dix ans au plus, d&rsquo;exercer une activit\u00e9 professionnelle ou b\u00e9n\u00e9vole impliquant un contact habituel avec des mineurs ;7\u00b0 l&rsquo;obligation d&rsquo;accomplir un stage de responsabilit\u00e9 parentale, selon les modalit\u00e9s fix\u00e9es \u00e0 l&rsquo;article  131-35-1 \u00bbIl est pr\u00e9cis\u00e9 que Madame [nom de naissance] b\u00e9n\u00e9ficiera de l\u2019int\u00e9gralit\u00e9 des allocations familiales.Ou si garde altern\u00e9eCompte tenu de la <a href=\"\/divorce\/definitions\/droit-de-garde\/\" rel=\"nofollow noopener\" title=\"\" target=\"\">garde altern\u00e9e<\/a>, les parents ne verseront pas de pension alimentaire \u00e0 xx. cependant chaque parent paiera l\u2019int\u00e9gralit\u00e9 des charges aff\u00e9rentes \u00e0 l\u2019enfant lors de son s\u00e9jour chez ledit parent. Il est pr\u00e9cis\u00e9 que les parents se r\u00e9partiront de moiti\u00e9 les autres charges pour l\u2019entretien et l\u2019\u00e9ducation de leur enfant.Ces dispositions seront r\u00e9visables en cas de fait nouveau.ou si majeurMonsieur [nom de l&rsquo;enfant majeur] n\u00e9 le [date de naissance] \u00e0 [ville de naissance] est majeur et  exerce une activit\u00e9 professionnelle r\u00e9mun\u00e9r\u00e9e non occasionnelle lui permettant de subvenir \u00e0 ses besoins, la contribution \u00e0 l\u2019entretien et \u00e0 l\u2019\u00e9ducation des enfants n\u2019est plus applicable.\n<\/p>\n<p>4 &#8211; Sur l\u2019assurance responsabilit\u00e9 civile :<\/p>\n<p align=\"justify\">Il est rappel\u00e9 que chacun des parents doit souscrire une assurance responsabilit\u00e9 civile chef de famille du fait des agissements de leur(s) enfant(s), et ce en application des dispositions de l\u2019article 1384 du code civil.<\/p>\n<p>5 &#8211; Sur la possibilit\u00e9 d\u2019audition de l\u2019enfant mineur par le juge aux affaires familiales :-       \tLes enfants ayant la facult\u00e9 de discernement:\n<\/p>\n<p>[nom des enfants]<\/p>\n<p align=\"justify\">Les \u00e9poux d\u00e9clarent avoir port\u00e9 \u00e0 la connaissance de leur(s) enfant(s) les mesures les concernant, ainsi que la possibilit\u00e9 de se faire entendre soit par le juge aux affaires familiales, soit par une autre personne d\u00e9sign\u00e9e par le juge, conform\u00e9ment aux dispositions de l\u2019article 388-1 du code civil. Un formulaire d\u2019information a \u00e9t\u00e9 adress\u00e9 \u00e0 chacun des enfants mineurs et est annex\u00e9 \u00e0 la pr\u00e9sente convention ; le(s) enfant(s) a (ont) compl\u00e9t\u00e9 le formulaire qui leur a \u00e9t\u00e9 transmis en pr\u00e9cisant qu\u2019il ne souhaitait(nt) pas faire usage de cette facult\u00e9.-          Les enfants n\u2019ayant pas la facult\u00e9 de discernement:<\/p>\n<p>  [nom des enfants]<\/p>\n<p align=\"justify\">Compte tenu du bas \u00e2ge de l\u2019enfant, il n\u2019a par cons\u00e9quent pas le discernement n\u00e9cessaire lui permettant d\u2019appr\u00e9cier les conditions de l\u2019article 388-1 du code civil ainsi que les cons\u00e9quences de son choix. aussi pour cette raison l\u2019information n\u2019a pu \u00eatre donn\u00e9e.<\/p>\n<h3>Convention de  liquidation du regime matrimonial :<\/h3>\n<p align=\"justify\">&#8211;\tDate d\u2019effet du divorce :Le divorce prendra effet entre les \u00e9poux \u00e0 la date \u00e0 laquelle la convention r\u00e9glant l\u2019ensemble des cons\u00e9quences du divorce acquiert force ex\u00e9cutoire.Par application des dispositions de l\u2019article 229-1 alin\u00e9a 3 du code civil, la convention acquiert date certaine et force ex\u00e9cutoire au jour du d\u00e9p\u00f4t au rang des minutes du notaire.ouOar exception aux dispositions de l\u2019article 262, les \u00e9poux ont convenu que les effets du divorce serait report\u00e9e au        , date de leur s\u00e9paration effective.Les \u00e9poux ne sont soumis \u00e0 aucun r\u00e9gime de protection des majeurs.- Immeuble :\n  <\/p>\n<h2 class=\"accordion-header\"> \u00a0\u00a0Sans bien immeuble<\/h2>\n<p align=\"justify\">Les \u00e9poux n\u2019ont pas de pr\u00eat immobilier et ne sont propri\u00e9taires d\u2019aucun bien immeuble en commun.<\/p>\n<h2 class=\"accordion-header\"> \u00a0\u00a0Possession d&rsquo;un bien immeuble<\/h2>\n<p align=\"justify\">Les \u00e9poux ont contract\u00e9 un pr\u00eat immobilier devant la banque [ nom ] pour l\u2019acquisition d\u2019un (nature : appartement, maison) d\u2019un montant initial de[montant ] \u20ac dont l\u2019encours s\u2019\u00e9l\u00e8ve \u00e0 ce jour \u00e0 [ montant]Madame \/ Monsieur       prendra en charge ledit pr\u00eat. la pleine propri\u00e9t\u00e9 du bien suscit\u00e9 lui reviendra apr\u00e8s le prononc\u00e9 du divorce moyennant le versement d\u2019une soulte.CF. <a href=\"\/divorce\/liquidation\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition acte liquidatif\" target=\"\">acte liquidatif <\/a>dress\u00e9 le [date], par ma\u00eetre [nom], notaire \u00e0 [ville]<\/p>\n<h2 class=\"accordion-header\"> \u00a0\u00a0Cas d&rsquo;un bien indivis<\/h2>\n<p align=\"justify\">Ledit bien restera un <a href=\"\/divorce\/definitions\/bien-indivis\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition bien indivis\" target=\"\">bien indivis <\/a>apr\u00e8s le prononc\u00e9 du divorce.cf. convention d\u2019indivision dress\u00e9e le [ date] par ma\u00eetre [nom], notaire \u00e0 [ville]<\/p>\n<\/p>\n<p align=\"justify\">&#8211;\tMeubles meublants :Le mobilier a fait l\u2019objet d\u2019un partage amiable \u00e9valu\u00e9 \u00e0 [ montant] euros.  ouIl n\u2019y a pas de <a href=\"\/divorce\/definitions\/bien-mobilier\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition bien mobilier\" target=\"\">bien mobilier<\/a> en commun-\tV\u00e9hicule :le v\u00e9hicule [marque du v\u00e9hicule] d&rsquo;une valeur de [montant]euros est attribu\u00e9 \u00e0 Madame [nom de naissance].le v\u00e9hicule [marque du v\u00e9hicule ] d&rsquo;une valeur de [montant] est attribu\u00e9 \u00e0 Monsieur [nom].-\tComptes bancaires :Les \u00e9poux ne disposent pas de compte en commun.Madame [nom de naissance] dispose d\u2019un compte courant ouvert \u00e0 la banque [nom de la banque] d\u2019un solde approximatif cr\u00e9diteur de [montant] \u20ac . Monsieur [nom] [pr\u00e9nom] renonce \u00e0 quelque r\u00e9compense que ce soit de ce chef.Monsieur [nom] dispose d\u2019un compte courant ouvert \u00e0 la banque [nom de la banque] \u00e0 d\u2019un solde approximatif cr\u00e9diteur de [montant]\u00a0\u20ac. Madame [nom de naissance] [pr\u00e9nom] renonce \u00e0 quelque r\u00e9compense que ce soit de ce chef.-\tEmprunts :Monsieur [nom] s\u2019engage \u00e0 prendre en charge le cr\u00e9dit contract\u00e9 aupr\u00e8s de la banque (ou \u00e9tablissement financier) [nom de la banque]\u00a0d\u2019un montant initial de [ montant] \u20ac et dont l\u2019encours s\u2019\u00e9l\u00e8ve \u00e0 ce jour \u00e0 la somme de [montant]\u00a0euros.Madame [nom de naissance] s\u2019engage \u00e9galement \u00e0 payer un cr\u00e9dit contract\u00e9 aupr\u00e8s de la banque [nom de la banque] d\u2019un montant initial de [montant] euros et dont l\u2019encours s\u2019\u00e9l\u00e8ve \u00e0 ce jour \u00e0 la somme de [montant]  euros .Monsieur [nom] a par ailleurs \u00e9mis des ch\u00e8ques sans provision d\u2019un montant total approximatif de [montant] \u20ac, il s\u2019engage \u00e9galement \u00e0 rembourser seul l\u2019int\u00e9gralit\u00e9.Les \u00e9poux d\u00e9clarent n\u2019avoir pas contract\u00e9 de (d\u2019autres) cr\u00e9dit(s) ou autre dette durant la vie commune.- Imp\u00f4t sur le revenu :Les d\u00e9clarations de revenus seront d\u00e9pos\u00e9es s\u00e9par\u00e9ment \u00e0 compter de l\u2019ann\u00e9e du jugement homologuant la convention.Pour l\u2019ann\u00e9e pr\u00e9c\u00e9dente, chacun des \u00e9poux paiera par moiti\u00e9 les imp\u00f4ts relatifs aux d\u00e9clarations communes. ouChacun des \u00e9poux r\u00e8glera l\u2019imp\u00f4t sur le revenu qui lui incombeouMonsieur [nom] ou Madame [nom de naissance] paiera l\u2019int\u00e9gralit\u00e9 des imp\u00f4ts relatifs aux d\u00e9clarations communes.- Imp\u00f4ts locaux :Les \u00e9poux paieront les imp\u00f4ts aff\u00e9rents (taxe d&rsquo;habitation) \u00e0 leur lieu d\u2019habitation.<\/p>\n<h3>D\u00e9p\u00f4t au rang des minutes du notaire<\/h3>\n<p align=\"justify\">La pr\u00e9sente convention sign\u00e9e par les \u00e9poux et leurs avocats sera d\u00e9pos\u00e9e au rang des minutes de ma\u00eetre [nom] , notaire \u00e0 [ville], qui sera charg\u00e9 de contr\u00f4ler le respect des exigences formelles pr\u00e9vues aux 1\u00b0 \u00e0 6\u00b0 de l\u2019article 229-3 du code civil.Le notaire devra \u00e9galement s\u2019assurer que le projet de convention n\u2019a pas \u00e9t\u00e9 sign\u00e9 avant l\u2019expiration du d\u00e9lai de r\u00e9flexion pr\u00e9vu \u00e0 l\u2019article 229-4 du code civil.A cet effet, seront annex\u00e9s aux pr\u00e9sentes les justificatifs d\u2019envois par lettre recommand\u00e9e avec avis de r\u00e9ception adress\u00e9s par chacun des avocats aux \u00e9poux.Ma\u00eetre gueguen-carroll est express\u00e9ment d\u00e9sign\u00e9 pour effectuer le d\u00e9p\u00f4t au rang des minutes du notaire ci-dessus d\u00e9sign\u00e9.Le d\u00e9p\u00f4t au rang des minutes interviendra au plus tard dans les sept jours suivants la date de la derni\u00e8re signature de la pr\u00e9sente convention par les \u00e9poux  et leurs avocats.Le notaire adressera, dans le d\u00e9lai de 15 jours l\u2019attestation de d\u00e9p\u00f4t au rang de ses minutes, comprenant l\u2019identit\u00e9 des \u00e9poux et la date du d\u00e9p\u00f4t ayant conf\u00e9r\u00e9 force ex\u00e9cutoire \u00e0 la convention.Ma\u00eetre gueguen-carroll. adressera deux exemplaires de la pr\u00e9sente convention rev\u00eatue de la formule ex\u00e9cutoire dans le d\u00e9lai maximum de dix jours apr\u00e8s la r\u00e9ception de l\u2019acte d\u00e9pos\u00e9 au <a href=\"\/divorce\/definitions\/rang-des-minutes\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition rang des minutes\" target=\"\">rang des minutes <\/a>du notaire ci-dessus d\u00e9sign\u00e9.Chacun des avocats adressera \u00e0 son client un exemplaire de la pr\u00e9sente convention rev\u00eatue de la formule ex\u00e9cutoire.<\/p>\n<h3>Transcription aupres des services d\u2019\u00e9tat civil<\/h3>\n<p align=\"justify\">Ma\u00eetre gueguen-carroll est express\u00e9ment d\u00e9sign\u00e9 pour effectuer les formalit\u00e9s de transcription du pr\u00e9sent divorce aupr\u00e8s des services de l\u2019\u00e9tat civil du lieu de mariage et des lieux de naissance des \u00e9poux, au vu de l\u2019attestation de d\u00e9p\u00f4t d\u00e9livr\u00e9e par le notaire.\u00c0 r\u00e9ception de la copie de l\u2019acte de mariage portant mention du divorce, il en adressera copie \u00e0 ma\u00eetre gueguen-carroll.Chacun des avocats adressera \u00e0 son client un exemplaire de l\u2019acte de mariage portant mention du divorce.<\/p>\n<h3>Frais de la procedure<\/h3>\n<p align=\"justify\">a \u2013 Co\u00fbt du divorce :Chaque \u00e9poux supportera par moiti\u00e9 le co\u00fbt du divorce et les honoraires.b &#8211;  droits d\u2019enregistrement :Les droits d\u2019enregistrement et de partage des pr\u00e9sentes seront pris en charge par les \u00e9poux par moiti\u00e9.Au moyen de la pr\u00e9sente convention, les \u00e9poux  d\u00e9clarent \u00eatre remplis de leurs droits et renoncent par cons\u00e9quent, express\u00e9ment \u00e0 \u00e9lever dans l\u2019avenir toute contestation \u00e0 ce sujet.<\/p>\n<h3>Affirmation de sincerite<\/h3>\n<p align=\"justify\">Les parties affirment sous les peines \u00e9dict\u00e9es par l\u2019article 1837 du cgi que le pr\u00e9sent acte ne contient aucune information ou dissimulation frauduleuse et qu\u2019il n\u2019a pas \u00e9t\u00e9 modifi\u00e9 ni contredit par aucune contre lettre.Elles reconnaissent avoir \u00e9t\u00e9 inform\u00e9es par leur conseil des peines encourues en cas d\u2019inexactitude des \u00e9l\u00e9ments qu\u2019elles ont d\u00e9clar\u00e9s sous leur propre responsabilit\u00e9.Elles d\u00e9clarent que leur identit\u00e9 est conforme \u00e0 celles expos\u00e9es en t\u00eate de la convention de divorce, qu\u2019elles ne sont pas dans un \u00e9tat civique, civil ou commercial mettant obstacle \u00e0 la libre disposition de leurs biens ou \u00e0 leur libre capacit\u00e9.<\/p>\n<h3>Information et conseils des parties<\/h3>\n<p align=\"justify\">Ma\u00eetre gueguen-carroll, conseil de Madame [nom de naissance]\u00bb, et ma\u00eetre [nom], conseil de Monsieur [nom], apr\u00e8s avoir donn\u00e9 lecture de cet acte aux parties et recueilli leurs signatures sur ledit acte, \u00e0 la date mentionn\u00e9e ci-apr\u00e8s, le contresignent, avec l\u2019accord des parties. conform\u00e9ment \u00e0 l\u2019article 66-3-1 de la loi du 31 d\u00e9cembre 1971, ces contreseings attestent que chacun d\u2019eux a pleinement \u00e9clair\u00e9 la partie qu\u2019il conseille sur les cons\u00e9quences juridiques de cet acte, ce que les parties reconnaissent, chacune pour ce qui la concerne. Chacun des avocats contresignataires de cet acte a personnellement v\u00e9rifi\u00e9 l\u2019identit\u00e9 et la capacit\u00e9 des signataires.Seront annex\u00e9es \u00e0 la pr\u00e9sente convention les pi\u00e8ces suivantes attestant de l\u2019identit\u00e9 et de la capacit\u00e9 des parties : pi\u00e8ce d\u2019identit\u00e9 de chacun des \u00e9poux (carte nationale d\u2019identit\u00e9 ou passeport) ; copie int\u00e9grale de l\u2019acte de mariage, des actes de naissance des \u00e9poux et des enfants (datant de moins de trois mois au jour de la signature de la convention)<\/p>\n<h3>Conservation de l\u2019acte d\u2019avocat<\/h3>\n<p align=\"justify\">1\u00b0 : Conservation par le site avosactes :Le pr\u00e9sent acte d\u2019avocat va faire l\u2019objet d\u2019un enregistrement et d\u2019une demande de conservation et d\u2019archivage aupr\u00e8s du service avosactes dont l\u2019adresse postale est : avosactes \u2013 scb \u2013 400, chemin des jallasi\u00e8res \u2013 cs 30002 \u2013 13150 eguillesLa conservation et l\u2019archivage des actes d\u2019avocat sont effectu\u00e9s pour une dur\u00e9e limit\u00e9e \u00e0 75 ans s\u2019agissant des supports num\u00e9ris\u00e9s et num\u00e9riques natifs, et sans limite de temps s\u2019agissant des documents conserv\u00e9s sur support papier.Ma\u00eetre gueguen-carroll est express\u00e9ment d\u00e9sign\u00e9 avocat d\u00e9posant et s\u2019engage \u00e0 effectuer les formalit\u00e9s n\u00e9cessaires aux fins d\u2019enregistrement, de conservation et d\u2019archivage du pr\u00e9sent acte d\u2019avocat aupr\u00e8s du service avosactes dans un d\u00e9lai de deux mois \u00e0 compter de la signature des pr\u00e9sentesLa d\u00e9livrance d\u2019un exemplaire num\u00e9rique de l\u2019acte d\u2019avocat pourra \u00eatre ult\u00e9rieurement sollicit\u00e9e par :\u2022\tl\u2019avocat d\u00e9posant qui est charg\u00e9 des formalit\u00e9s d\u2019enregistrement du pr\u00e9sent acte d\u2019avocat\u2022\tles avocats autres que l\u2019avocat d\u00e9posant, qui ont \u00e9galement appos\u00e9 leur contreseing sur le pr\u00e9sent acte\u2022\tl\u2019une des parties signataires, en vertu d\u2019un mandat expr\u00e8s qu\u2019elle donnera \u00e0 son conseil, si celui-ci n\u2019est ni l\u2019avocat d\u00e9posant, ni l\u2019un des avocats qui ont appos\u00e9 leur contreseing sur le pr\u00e9sent acte.Le contenu de l\u2019acte ne fait l\u2019objet en aucune fa\u00e7on d\u2019un quelconque traitement informatique.<\/p>\n<h3>Information cnil <\/h3>\n<p align=\"justify\">Les informations recueillies lors de l\u2019enregistrement du pr\u00e9sent acte aupr\u00e8s du services avosactes font l\u2019objet d\u2019un traitement informatique d\u00e9clar\u00e9 aupr\u00e8s de la commission de l\u2019informatique et des libert\u00e9s (cnil n\u00b01711565 v 0). le contenu de l\u2019acte ne fait l\u2019objet en aucune fa\u00e7on d\u2019un quelconque traitement informatique.Les donn\u00e9es recueillies sont seulement destin\u00e9es \u00e0 assurer l\u2019archivage et la tra\u00e7abilit\u00e9 du pr\u00e9sent acte afin de pouvoir en d\u00e9livrer copie selon les modalit\u00e9s d\u00e9crites dans la \u00ab clause relative \u00e0 la conservation de l\u2019<a href=\"\/divorce\/definitions\/acte-avocat\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition acte d'avocat\" target=\"\">acte d\u2019avocat<\/a> \u00bbConcernant les personnes physiques, il s\u2019agit de la date de l\u2019acte, la nature de l\u2019acte sign\u00e9, les coordonn\u00e9es de l\u2019acte qui les a conseill\u00e9es, les \u00e9l\u00e9ments d\u2019identification relatifs \u00e0 leur \u00e9tat civil : nom patronymique, pr\u00e9nom, date de naissance et adresse.De convention expresse, par les pr\u00e9sentes, les personnes physiques, parties signataires et avocats utilisateurs, dont les informations personnelles susvis\u00e9es ont \u00e9t\u00e9 transmises au service avosactes, renoncent \u00e0 s\u2019opposer au traitement de ces informations, ainsi qu\u2019il est dit \u00e0 l\u2019article 38 al. 3 de la loi 78-17 du 6 janvier 1978.En revanche, ces personnes b\u00e9n\u00e9ficient d\u2019un droit d\u2019acc\u00e8s, de modification et de rectification des donn\u00e9es qui les concernent conform\u00e9ment aux dispositions de l\u2019article 40 de la loi 78-17 du 6 janvier 1978.les demandes sont \u00e0 adresser au responsable de traitement, exploitant du service avosactes \u2013 scb \u2013 400, chemin des jallasi\u00e8res \u2013 cs 30002 -13510 eguillesou 2\u00b0 : Conservation par e-barreau :Le pr\u00e9sent acte d\u2019avocat va faire l\u2019objet d\u2019un enregistrement et d\u2019un archivage aupr\u00e8s du service e-barreau.Ma\u00eetre [nom] est express\u00e9ment d\u00e9sign\u00e9 avocat d\u00e9posant et s\u2019engage \u00e0 effectuer les formalit\u00e9s n\u00e9cessaires aux fins d\u2019enregistrement, de conservation et d\u2019archivage du pr\u00e9sent acte d\u2019avocat aupr\u00e8s du service e-barreau dans un d\u00e9lai de deux mois \u00e0 compter de la signature des pr\u00e9sentes.Les \u00e9poux sont inform\u00e9s que le conseil national des barreaux met en \u0153uvre un traitement de donn\u00e9es \u00e0 caract\u00e8re personnel, dont il est responsable, ayant pour finalit\u00e9 la gestion de la plateforme acte d&rsquo;avocat et de ses fonctionnalit\u00e9s et notamment la r\u00e9alisation d&rsquo;actes, la signature \u00e9lectronique de ces actes, leur horodatage et leur archivage. Les donn\u00e9es collect\u00e9es sont indispensables \u00e0 ce traitement. Ces donn\u00e9es sont destin\u00e9es aux services habilit\u00e9s du conseil national des barreaux ainsi que, le cas \u00e9ch\u00e9ant, \u00e0 ses sous-traitants ou prestataires. Conform\u00e9ment aux dispositions de la loi du 6 janvier 1978, les parties disposent d&rsquo;un droit d&rsquo;interrogation, d&rsquo;acc\u00e8s et de rectification des donn\u00e9es les concernant, ainsi que d&rsquo;un droit d&rsquo;opposition pour motif l\u00e9gitime \u00e0 ce que les donn\u00e9es \u00e0 caract\u00e8re personnel vous concernant fassent l&rsquo;objet d&rsquo;un traitement. Ces droits s&rsquo;exercent par courrier accompagn\u00e9 d&rsquo;une copie d&rsquo;un titre d&rsquo;identit\u00e9 sign\u00e9 \u00e0 l&rsquo;adresse postale suivante : conseil national des barreaux, service informatique, 22 rue de londres, 75009 paris ou par courriel \u00e0 <a href=\"mailto:donneespersonnelles@cnb.avocat.fr\">donneespersonnelles@cnb.avocat.fr<\/a>.<\/p>\n<h3>Recours a une procedure participative<\/h3>\n<p align=\"justify\">En cas de difficult\u00e9 d\u2019ex\u00e9cution des pr\u00e9sentes et de leur suite, et notamment en cas de survenance d\u2019un \u00e9l\u00e9ment  nouveau en ce qui concerne la r\u00e9sidence des enfants, les droits de visites et d\u2019h\u00e9bergement, les pensions alimentaires et prestation compensatoire,  les parties conviennent de recourir avant toute saisine des juridictions \u00e0 une convention de proc\u00e9dure participative telle que r\u00e9gie par les articles 2062 \u00e0 2068 du code civil.La proc\u00e9dure participative sera d\u2019une dur\u00e9e minimum de 6 mois, les parties s\u2019engageant \u00e0 \u0153uvrer conjointement et de bonne foi \u00e0 la r\u00e9solution amiable de leur \u00e9ventuel diff\u00e9rend.Les \u00e9poux sont inform\u00e9s que l\u2019absence de mise en \u0153uvre de la proc\u00e9dure participative, pr\u00e9vue au pr\u00e9sent paragraphe, rend irrecevable tout recours au juge pour qu\u2019il statue sur <a href=\"\/divorce\/definitions\/litige\/\" rel=\"nofollow noopener\" title=\"D\u00e9finition litige\" target=\"_parent\">le litige<\/a>.<\/p>\n<h3>D\u00e9lai de reflexion<\/h3>\n<p align=\"justify\">En application des dispositions de l\u2019article 229-4 du code civil, le projet de la pr\u00e9sente convention de divorce a \u00e9t\u00e9 adress\u00e9 aux \u00e9poux au moins quinze jours avant la signature des pr\u00e9sentes ;Ma\u00eetre gueguen-carroll, conseil de Madame [nom de naissance], a adress\u00e9 le projet de convention par lettre recommand\u00e9e avec avis de r\u00e9ception le [date d&rsquo;envoi], re\u00e7ue le [date de r\u00e9ception]  Ma\u00eetre [nom], conseil de Monsieur\u00a0[nom], a adress\u00e9 le projet de convention par lettre recommand\u00e9e avec avis de r\u00e9ception le [date d&rsquo;envoi], re\u00e7ue le\u00a0[date de r\u00e9ception]  Apr\u00e8s avoir constat\u00e9 que le d\u00e9lai de r\u00e9flexion pr\u00e9vu \u00e0 l\u2019article 229-4 du code civil \u00e9tait expir\u00e9, les \u00e9poux, assist\u00e9s de leurs conseils respectifs, ont confirm\u00e9 leur intention de consentir mutuellement \u00e0 leur divorce et ont appos\u00e9 leurs signatures au bas des pr\u00e9sentes.<\/p>\n<p>\nMadame [nom de naissance] \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Monsieur [nom ]<\/p>\n<p>Me Gueguen-carrollAvocatRappel: article 1477 du code civil : celui qui aurait dissimul\u00e9 sciemment l\u2019existence d\u2019une dette commune doit l\u2019assumer d\u00e9finitivement.<\/p>\n<p align=\"right\">fait \u00e0 paris, le [date]en 4 exemplaires originaux<\/p>\n<\/p>\n<p>PI\u00c8CES ANNEX\u00c9ES \u00c0 LA CONVENTIONPAR CONSENTEMENT MUTUEL ENTRE LES \u00c9POUX<br \/>\ncarte d\u2019identit\u00e9 ou passeport de Madame [NOM DE NAISSANCE]<br \/>\ncarte d\u2019identit\u00e9 ou passeport de Monsieur [NOM]<br \/>\ncopie du livret de famille<br \/>\ncopie int\u00e9grale datant de moins de 3 mois des actes suivants :* acte de mariage* acte de naissance de Madame[NOM DE NAISSANCE]* acte de naissance de Monsieur [NOM]* acte(s) de naissance de(s) enfant(s)<br \/>\nformulaire d\u2019information adress\u00e9 \u00e0 chacun des enfants mineurs en application des dispositions de l\u2019article 388-1 du code civil compl\u00e9t\u00e9 par chacun d\u2019eux.<br \/>\nd\u00e9claration sur l\u2019honneur de chacun des \u00e9poux conform\u00e9ment aux dispositions de l\u2019article 272 du code civil.<br \/>\njustificatif de l&rsquo;envoi par lrar du projet de convention de divorce \u00e0 chacun des \u00e9poux.<\/p>\n<p>Eventuellement :\n<\/p>\n<p>copie du contrat de mariage<br \/>\nacte notari\u00e9 (\u00e9tat liquidatif ou convention d\u2019indivision)<\/p>\n<p><a href=\"\/divorce\/avocat-divorce\/mourmelon-le-grand\/\" rel=\"nofollow\"> \u25c4 Avocat divorce sans juge Mourmelon-le-Grand (51)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u25c4 Avocat divorce sans juge Mourmelon-le-Grand (51) T\u00e9l\u00e9charger Convention avocat divorce sans juge Mourmelon-le-Grand (51) MOD\u00c8LE DE CONVENTION DIVORCE SANS JUGEMOURMELON-LE-GRAND (51)Portant r\u00e8glement complet des effets du divorce (Article 229 et suiv. du Code Civil, 1374, 1193 et 1195 du Code civil, Article 66-3-1 de la loi du 31 D\u00e9cembre 1971 portant r\u00e9forme de certaines [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3060,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"priorite":[],"class_list":["post-4197","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce<\/title>\n<meta name=\"description\" content=\"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l&#039;amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce\" \/>\n<meta property=\"og:description\" content=\"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l&#039;amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/\" \/>\n<meta property=\"og:site_name\" content=\"Avocat GC - Avocat Divorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/convention-mourmelon-le-grand\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/convention-mourmelon-le-grand\\\/\",\"name\":\"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\"},\"datePublished\":\"2018-06-03T00:00:00+00:00\",\"description\":\"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l'amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/convention-mourmelon-le-grand\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/convention-mourmelon-le-grand\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/convention-mourmelon-le-grand\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divorce sans juge\",\"item\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/divorce-sans-juge\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#website\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"name\":\"Avocat GC - Avocat Divorce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#organization\",\"name\":\"Avocat GC - Avocat Divorce\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"contentUrl\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Sans-titre.png\",\"width\":200,\"height\":180,\"caption\":\"Avocat GC - Avocat Divorce\"},\"image\":{\"@id\":\"https:\\\/\\\/avocat-gc.com\\\/divorce\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce","description":"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l'amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/","og_locale":"fr_FR","og_type":"article","og_title":"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce","og_description":"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l'amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements","og_url":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/","og_site_name":"Avocat GC - Avocat Divorce","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/","url":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/","name":"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention - Avocat Divorce","isPartOf":{"@id":"https:\/\/avocat-gc.com\/divorce\/#website"},"datePublished":"2018-06-03T00:00:00+00:00","description":"Comment divorcer sans juge \u00e0 Mourmelon-le-Grand (51) ? T\u00e9l\u00e9charger notre mod\u00e8le de convention de divorce dans la Marne et divorcez sans juge,\u00e0 l'amiable, en 1 mois seulement. Contactez notre cabinet au \u260e T\u00e9l. 01.47.04.25.40 pour davantage de renseignements","breadcrumb":{"@id":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/convention-mourmelon-le-grand\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/avocat-gc.com\/divorce\/"},{"@type":"ListItem","position":2,"name":"Divorce sans juge","item":"https:\/\/avocat-gc.com\/divorce\/divorce-sans-juge\/"},{"@type":"ListItem","position":3,"name":"Divorce sans Juge Mourmelon-le-Grand : Exemple de convention"}]},{"@type":"WebSite","@id":"https:\/\/avocat-gc.com\/divorce\/#website","url":"https:\/\/avocat-gc.com\/divorce\/","name":"Avocat GC - Avocat Divorce","description":"","publisher":{"@id":"https:\/\/avocat-gc.com\/divorce\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avocat-gc.com\/divorce\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avocat-gc.com\/divorce\/#organization","name":"Avocat GC - Avocat Divorce","url":"https:\/\/avocat-gc.com\/divorce\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/","url":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","contentUrl":"https:\/\/avocat-gc.com\/divorce\/wp-content\/uploads\/2024\/04\/cropped-Sans-titre.png","width":200,"height":180,"caption":"Avocat GC - Avocat Divorce"},"image":{"@id":"https:\/\/avocat-gc.com\/divorce\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/4197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/comments?post=4197"}],"version-history":[{"count":0,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/4197\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/pages\/3060"}],"wp:attachment":[{"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/media?parent=4197"}],"wp:term":[{"taxonomy":"priorite","embeddable":true,"href":"https:\/\/avocat-gc.com\/divorce\/wp-json\/wp\/v2\/priorite?post=4197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}